{"id":2324,"date":"2022-07-29T15:36:57","date_gmt":"2022-07-29T15:36:57","guid":{"rendered":"https:\/\/cascinadelpozzo.com\/home\/"},"modified":"2025-02-27T08:19:32","modified_gmt":"2025-02-27T07:19:32","slug":"home","status":"publish","type":"page","link":"https:\/\/cascinadelpozzo.com\/en\/","title":{"rendered":"Home"},"content":{"rendered":"<style>.kb-row-layout-id6_43fb7a-cd > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6_43fb7a-cd > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6_43fb7a-cd > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id6_43fb7a-cd > .kt-row-layout-overlay{opacity:0.23;background-color:var(--global-palette3, #1A202C);}@media all and (max-width: 1024px){.kb-row-layout-id6_43fb7a-cd > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id6_43fb7a-cd > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6_43fb7a-cd alignfull has-theme-palette4-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-blocks-carousel kb-blocks-bg-slider kt-carousel-container-dotstyle-none\"><div class=\"kt-blocks-carousel-init splide kb-blocks-bg-slider-init kt-carousel-arrowstyle-none kt-carousel-dotstyle-none\" data-slider-anim-speed=\"1400\" data-slider-type=\"slider\" data-slider-scroll=\"1\" data-slider-arrows=\"false\" data-slider-fade=\"true\" data-slider-dots=\"false\" data-slider-hover-pause=\"false\" data-slider-auto=\"true\" data-slider-speed=\"3000\" data-show-pause-button=\"false\"><div class=\"splide__track\"><ul class=\"splide__list\"><li class=\"splide__slide kb-bg-slide-contain\"><div  class=\"kb-bg-slide kb-bg-slide-0\" style=\"background-image:url(https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/09\/viticastellinaldo.jpg); background-size:cover; background-position:center center; background-repeat:no-repeat;\"><\/div><\/li><li class=\"splide__slide kb-bg-slide-contain\"><div  class=\"kb-bg-slide kb-bg-slide-1\" style=\"background-image:url(https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/famiglia-cascinadelpozzo.jpg); background-size:cover; background-position:center center; background-repeat:no-repeat;\"><\/div><\/li><li class=\"splide__slide kb-bg-slide-contain\"><div  class=\"kb-bg-slide kb-bg-slide-2\" style=\"background-image:url(https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/vendemmia-castellinaldo-cascinadelpozzo.jpg); background-size:cover; background-position:center center; background-repeat:no-repeat;\"><\/div><\/li><li class=\"splide__slide kb-bg-slide-contain\"><div  class=\"kb-bg-slide kb-bg-slide-3\" style=\"background-image:url(https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/fratelli-papa-marchisio.jpg); background-size:cover; background-position:center center; background-repeat:no-repeat;\"><\/div><\/li><li class=\"splide__slide kb-bg-slide-contain\"><div  class=\"kb-bg-slide kb-bg-slide-4\" style=\"background-image:url(https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/colline-roero.jpg); background-size:cover; background-position:center center; background-repeat:no-repeat;\"><\/div><\/li><\/ul><\/div><\/div><\/div><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column6_421cb9-67 > .kt-inside-inner-col{display:flex;}.kadence-column6_421cb9-67 > .kt-inside-inner-col{padding-bottom:0px;}.kadence-column6_421cb9-67 > .kt-inside-inner-col,.kadence-column6_421cb9-67 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6_421cb9-67 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6_421cb9-67 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column6_421cb9-67 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column6_421cb9-67{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_421cb9-67{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_421cb9-67 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column6_421cb9-67 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6_421cb9-67{position:relative;}.kadence-column6_421cb9-67, .kt-inside-inner-col > .kadence-column6_421cb9-67:not(.specificity){margin-bottom:0px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column6_421cb9-67{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_421cb9-67{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_421cb9-67 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column6_421cb9-67 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column6_421cb9-67{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_421cb9-67{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_421cb9-67 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column6_421cb9-67 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6_421cb9-67 kb-section-dir-vertical inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-6_f2a927-76 .kt-block-spacer{height:600px;}.wp-block-kadence-spacer.kt-block-spacer-6_f2a927-76 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-6_f2a927-76\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-6_7be16f-45 .kt-block-spacer{height:130px;}.wp-block-kadence-spacer.kt-block-spacer-6_7be16f-45 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-6_7be16f-45\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id6_9d4cfb-d3 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6_9d4cfb-d3 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6_9d4cfb-d3 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id6_9d4cfb-d3 > .kt-row-layout-overlay{opacity:0.00;background-color:var(--global-palette9, #ffffff);}@media all and (max-width: 1024px){.kb-row-layout-id6_9d4cfb-d3 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id6_9d4cfb-d3 > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6_9d4cfb-d3 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column6_d3d16a-57 > .kt-inside-inner-col{display:flex;}.kadence-column6_d3d16a-57 > .kt-inside-inner-col{padding-bottom:0px;}.kadence-column6_d3d16a-57 > .kt-inside-inner-col,.kadence-column6_d3d16a-57 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6_d3d16a-57 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6_d3d16a-57 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column6_d3d16a-57 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column6_d3d16a-57{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_d3d16a-57{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_d3d16a-57 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column6_d3d16a-57 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6_d3d16a-57{position:relative;}.kadence-column6_d3d16a-57, .kt-inside-inner-col > .kadence-column6_d3d16a-57:not(.specificity){margin-bottom:0px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column6_d3d16a-57{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_d3d16a-57{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_d3d16a-57 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column6_d3d16a-57 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column6_d3d16a-57{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_d3d16a-57{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_d3d16a-57 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column6_d3d16a-57 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6_d3d16a-57 kb-section-dir-vertical inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading6_ac4985-3b, .wp-block-kadence-advancedheading.kt-adv-heading6_ac4985-3b[data-kb-block=\"kb-adv-heading6_ac4985-3b\"]{padding-bottom:var(--global-kb-spacing-sm, 1.5rem);text-align:center;font-size:var(--global-kb-font-size-sm, 0.9rem);font-weight:400;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading6_ac4985-3b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading6_ac4985-3b[data-kb-block=\"kb-adv-heading6_ac4985-3b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading6_ac4985-3b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading6_ac4985-3b[data-kb-block=\"kb-adv-heading6_ac4985-3b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading6_ac4985-3b wp-block-kadence-advancedheading has-theme-palette-4-color has-text-color\" data-kb-block=\"kb-adv-heading6_ac4985-3b\">UN BENVENUTO DALLA FAMIGLIA MARCHISIO<\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading6_73faab-76, .wp-block-kadence-advancedheading.kt-adv-heading6_73faab-76[data-kb-block=\"kb-adv-heading6_73faab-76\"]{padding-top:0px;padding-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-top:0px;margin-bottom:0px;text-align:center;font-size:var(--global-kb-font-size-xxl, 4rem);line-height:1;font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading6_73faab-76 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading6_73faab-76[data-kb-block=\"kb-adv-heading6_73faab-76\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading6_73faab-76 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading6_73faab-76[data-kb-block=\"kb-adv-heading6_73faab-76\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading6_73faab-76 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading6_73faab-76\">Winemakers in the Roero for five generations<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading6_a105a3-0e, .wp-block-kadence-advancedheading.kt-adv-heading6_a105a3-0e[data-kb-block=\"kb-adv-heading6_a105a3-0e\"]{max-width:896px;margin-right:auto;margin-left:auto;padding-top:0px;padding-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-top:0px;margin-bottom:0px;text-align:center;font-size:var(--global-kb-font-size-md, 1.25rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading6_a105a3-0e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading6_a105a3-0e[data-kb-block=\"kb-adv-heading6_a105a3-0e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading6_a105a3-0e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading6_a105a3-0e[data-kb-block=\"kb-adv-heading6_a105a3-0e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading6_a105a3-0e wp-block-kadence-advancedheading has-theme-palette-4-color has-text-color\" data-kb-block=\"kb-adv-heading6_a105a3-0e\">Since the early 1900s, the Marchisio Family has worked together with the land of Castellinaldo to produce wine at the Pozzo vineyard. It is from here that Cascina del Pozzo takes its name.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kt-btns6_6fb008-55, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns6_6fb008-55, .wp-block-kadence-advancedbtn.kb-btns6_6fb008-55, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns6_6fb008-55{margin-bottom:0px;}.wp-block-kadence-advancedbtn.kb-btns6_6fb008-55{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns6_6fb008-55 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns6_6fb008-55\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn6_2ab5a0-19.kb-button{width:initial;}<\/style><a class=\"kb-button kt-button button kb-btn6_2ab5a0-19 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/cascinadelpozzo.com\/en\/company\/\"><span class=\"kt-btn-inner-text\">OUR HISTORY<\/span><\/a>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn6_663e16-19.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn6_663e16-19.kb-button{color:var(--global-palette4, #2D3748);background:var(--global-palette7, #EDF2F7);}.wp-block-kadence-advancedbtn .kb-btn6_663e16-19.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn6_663e16-19.kb-button:focus{background:var(--global-palette2, #2B6CB0);}<\/style><a class=\"kb-button kt-button button kb-btn6_663e16-19 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/cascinadelpozzo.com\/en\/wines\/\"><span class=\"kt-btn-inner-text\">OUR WINES.<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id6_20651a-71 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6_20651a-71 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6_20651a-71 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id6_20651a-71 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6_20651a-71 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id6_20651a-71 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6_20651a-71 alignnone has-theme-palette3-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column6_05beaf-cd > .kt-inside-inner-col,.kadence-column6_05beaf-cd > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6_05beaf-cd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6_05beaf-cd > .kt-inside-inner-col{flex-direction:column;}.kadence-column6_05beaf-cd > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6_05beaf-cd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6_05beaf-cd{position:relative;}@media all and (max-width: 1024px){.kadence-column6_05beaf-cd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6_05beaf-cd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6_05beaf-cd\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading6_cc2a36-5f, .wp-block-kadence-advancedheading.kt-adv-heading6_cc2a36-5f[data-kb-block=\"kb-adv-heading6_cc2a36-5f\"]{padding-bottom:0px;margin-bottom:0px;text-align:center;font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;border-bottom:0px solid var(--global-palette2, #2B6CB0);}.wp-block-kadence-advancedheading.kt-adv-heading6_cc2a36-5f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading6_cc2a36-5f[data-kb-block=\"kb-adv-heading6_cc2a36-5f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading6_cc2a36-5f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading6_cc2a36-5f[data-kb-block=\"kb-adv-heading6_cc2a36-5f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading6_cc2a36-5f, .wp-block-kadence-advancedheading.kt-adv-heading6_cc2a36-5f[data-kb-block=\"kb-adv-heading6_cc2a36-5f\"]{border-bottom:0px solid var(--global-palette2, #2B6CB0);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading6_cc2a36-5f, .wp-block-kadence-advancedheading.kt-adv-heading6_cc2a36-5f[data-kb-block=\"kb-adv-heading6_cc2a36-5f\"]{border-bottom:0px solid var(--global-palette2, #2B6CB0);}}<\/style>\n<h3 class=\"kt-adv-heading6_cc2a36-5f wp-block-kadence-advancedheading has-theme-palette-2-color has-text-color\" data-kb-block=\"kb-adv-heading6_cc2a36-5f\">Wines<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading6_96636b-3d, .wp-block-kadence-advancedheading.kt-adv-heading6_96636b-3d[data-kb-block=\"kb-adv-heading6_96636b-3d\"]{padding-bottom:0px;margin-bottom:0px;text-align:center;font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading6_96636b-3d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading6_96636b-3d[data-kb-block=\"kb-adv-heading6_96636b-3d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading6_96636b-3d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading6_96636b-3d[data-kb-block=\"kb-adv-heading6_96636b-3d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading6_96636b-3d wp-block-kadence-advancedheading has-theme-palette-2-color has-text-color\" data-kb-block=\"kb-adv-heading6_96636b-3d\">Discover our wines<\/p>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-6_98fb3f-ee .kt-block-spacer{height:10px;}.wp-block-kadence-spacer.kt-block-spacer-6_98fb3f-ee .kt-divider{border-top-width:2px;border-top-color:var(--global-palette2, #2B6CB0);width:13%;border-top-style:dotted;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-6_98fb3f-ee\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.kb-portfolio-loop6_d51f08-3f.kb-portfolio-grid-layout-fluidcarousel.kt-blocks-carousel .kadence-portfolio-image, .kb-portfolio-loop6_d51f08-3f.kb-portfolio-grid-layout-fluidcarousel.kt-blocks-carousel .kadence-portfolio-image .kadence-portfolio-image-intrisic .kadence-portfolio-image-inner-intrisic img{height:300px;}.kb-portfolio-loop6_d51f08-3f .kb-blocks-portfolio-grid-item{border-top:1px solid;border-right:1px solid;border-bottom:1px solid;border-left:1px solid;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kb-portfolio-loop6_d51f08-3f .kb-portfolio-overlay-color{background-color:rgba(255, 255, 255, 0);}.kb-portfolio-loop6_d51f08-3f .kb-portfolio-overlay-border{border-top:1px solid;border-right:1px solid;border-bottom:1px solid;border-left:1px solid;}.kb-portfolio-loop6_d51f08-3f .kb-blocks-portfolio-grid-item:hover .kb-portfolio-overlay-color{background-color:var(--global-palette3, #1A202C);}.kb-portfolio-loop6_d51f08-3f .kb-blocks-portfolio-grid-item:hover .kb-portfolio-overlay-border{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}.kb-portfolio-loop6_d51f08-3f .kb-blocks-portfolio-grid-item .entry-title{color:var(--global-palette1, #3182CE);padding:5px 10px 10px 10px;margin:0px 0px 0px 0px;font-size:16px;text-transform:none;}.kb-portfolio-loop6_d51f08-3f .kb-filter-item{border-width:0px 0px 2px 0px;padding:5px 8px 5px 8px;margin:0px 10px 0px 0px;}.kb-portfolio-loop6_d51f08-3f{padding-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-top:var(--global-kb-spacing-lg, 3rem);}.kb-portfolio-loop6_d51f08-3f .kb-portfolio-grid-pause-button{color:#fff;background-color:transparent;border:2px solid #fff;}@media all and (max-width: 1024px){.kb-portfolio-loop6_d51f08-3f.kb-portfolio-grid-layout-fluidcarousel.kt-blocks-carousel .kadence-portfolio-image, .kb-portfolio-loop6_d51f08-3f.kb-portfolio-grid-layout-fluidcarousel.kt-blocks-carousel .kadence-portfolio-image .kadence-portfolio-image-intrisic .kadence-portfolio-image-inner-intrisic img{height:300px;}}@media all and (max-width: 1024px){.kb-portfolio-loop6_d51f08-3f .kb-blocks-portfolio-grid-item{border-top:1px solid;border-right:1px solid;border-bottom:1px solid;border-left:1px solid;}}@media all and (max-width: 1024px){.kb-portfolio-loop6_d51f08-3f .kb-portfolio-overlay-border{border-top:1px solid;border-right:1px solid;border-bottom:1px solid;border-left:1px solid;}}@media all and (max-width: 1024px){.kb-portfolio-loop6_d51f08-3f .kb-blocks-portfolio-grid-item:hover .kb-portfolio-overlay-border{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.kb-portfolio-loop6_d51f08-3f.kb-portfolio-grid-layout-fluidcarousel.kt-blocks-carousel .kadence-portfolio-image, .kb-portfolio-loop6_d51f08-3f.kb-portfolio-grid-layout-fluidcarousel.kt-blocks-carousel .kadence-portfolio-image .kadence-portfolio-image-intrisic .kadence-portfolio-image-inner-intrisic img{height:300px;}.kb-portfolio-loop6_d51f08-3f .kb-blocks-portfolio-grid-item{background-color:var(--global-palette3, #1A202C);border-top:1px solid;border-right:1px solid;border-bottom:1px solid;border-left:1px solid;}.kb-portfolio-loop6_d51f08-3f .kb-portfolio-overlay-border{border-top:1px solid;border-right:1px solid;border-bottom:1px solid;border-left:1px solid;}.kb-portfolio-loop6_d51f08-3f .kb-blocks-portfolio-grid-item:hover .kb-portfolio-overlay-border{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}<\/style><div class=\" wp-block-kadence-portfoliogrid kb-blocks-portfolio-loop-block alignnone kb-portfolio-loop6_d51f08-3f kb-portfolio-grid-layout-fluidcarousel kt-blocks-carousel \"><div class=\" kb-portfolio-grid-layout-fluidcarousel-wrap kt-post-grid-layout-carousel-wrap kt-carousel-arrowstyle-outlinewhite kt-carousel-dotstyle-outlinelight splide kb-blocks-portfolio-img-hover-static kb-blocks-portfolio-content-hover-static\" data-columns-xxl=\"5\" data-columns-xl=\"5\" data-columns-md=\"5\" data-columns-sm=\"4\" data-columns-xs=\"4\" data-columns-ss=\"3\" data-slider-center-mode=\"true\" data-slider-type=\"fluidcarousel\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-dots=\"true\" data-slider-arrows=\"true\" data-slider-hover-pause=\"false\" data-slider-auto=\"true\" data-slider-center-mode=\"true\" data-slider-speed=\"4000\" data-show-pause-button=\"false\" data-slider-gap=\"0\" data-slider-gap-tablet=\"0\" data-slider-gap-mobile=\"0\" data-slider-gap-unit=\"px\" data-item-selector=\".kb-portfolio-masonry-item\"><div class=\"kadence-splide-slider-init splide__track\"><ul><li class=\"kb-portfolio-slider-item kb-slide-item\"><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:176.8%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"884\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/alba-bricco-serra.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/alba-bricco-serra.png 500w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/alba-bricco-serra-170x300.png 170w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/cascinadelpozzo.com\/en\/wines\/alba-bricco-serra\/\" aria-label=\"Alba Bricco Serra\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h3 class=\"entry-title kb-portfolio-loop-title\">Alba Bricco Serra<\/h3><\/div><\/div><\/div><\/div><\/li><li class=\"kb-portfolio-slider-item kb-slide-item\"><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:176.8%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"884\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/roero-riserva-serra-zoanni.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/roero-riserva-serra-zoanni.png 500w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/roero-riserva-serra-zoanni-170x300.png 170w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/cascinadelpozzo.com\/en\/wines\/roero-riserva-serra-zoanni\/\" aria-label=\"Roero Riserva Serra Zoanni\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h3 class=\"entry-title kb-portfolio-loop-title\">Roero Riserva Serra Zoanni<\/h3><\/div><\/div><\/div><\/div><\/li><li class=\"kb-portfolio-slider-item kb-slide-item\"><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:176.8%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"884\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/roeromontegalletto.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/roeromontegalletto.png 500w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/roeromontegalletto-170x300.png 170w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/cascinadelpozzo.com\/en\/wines\/roero-montegalletto\/\" aria-label=\"Roero Montegalletto\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h3 class=\"entry-title kb-portfolio-loop-title\">Roero Montegalletto<\/h3><\/div><\/div><\/div><\/div><\/li><li class=\"kb-portfolio-slider-item kb-slide-item\"><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:176.8%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"884\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/nebbiolodalba-caplavur.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/nebbiolodalba-caplavur.png 500w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/nebbiolodalba-caplavur-170x300.png 170w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/cascinadelpozzo.com\/en\/wines\/nebbiolo-dalba-caplavur\/\" aria-label=\"Nebbiolo d&#8217;Alba Caplavur\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h3 class=\"entry-title kb-portfolio-loop-title\">Nebbiolo d&#8217;Alba Caplavur<\/h3><\/div><\/div><\/div><\/div><\/li><li class=\"kb-portfolio-slider-item kb-slide-item\"><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:176.8%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"884\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/nebbiolodalba-vignavalmaggiore.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/nebbiolodalba-vignavalmaggiore.png 500w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/nebbiolodalba-vignavalmaggiore-170x300.png 170w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/cascinadelpozzo.com\/en\/wines\/nebbiolo-dalba-vigna-valmaggiore\/\" aria-label=\"Nebbiolo d&#8217;Alba Vigna Valmaggiore\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h3 class=\"entry-title kb-portfolio-loop-title\">Nebbiolo d&#8217;Alba Vigna Valmaggiore<\/h3><\/div><\/div><\/div><\/div><\/li><li class=\"kb-portfolio-slider-item kb-slide-item\"><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:176.8%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"884\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/barberadalba-castellinaldo.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/barberadalba-castellinaldo.png 500w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/barberadalba-castellinaldo-170x300.png 170w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/cascinadelpozzo.com\/en\/wines\/castellinaldo-barbera-dalba\/\" aria-label=\"Castellinaldo Barbera d&#8217;Alba\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h3 class=\"entry-title kb-portfolio-loop-title\">Castellinaldo Barbera d&#8217;Alba<\/h3><\/div><\/div><\/div><\/div><\/li><li class=\"kb-portfolio-slider-item kb-slide-item\"><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:176.8%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"884\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/barberadalba-fossamara.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/barberadalba-fossamara.png 500w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/barberadalba-fossamara-170x300.png 170w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/cascinadelpozzo.com\/en\/wines\/barbera-dalba-fossamara\/\" aria-label=\"Barbera d&#8217;Alba Fossamara\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h3 class=\"entry-title kb-portfolio-loop-title\">Barbera d&#8217;Alba Fossamara<\/h3><\/div><\/div><\/div><\/div><\/li><li class=\"kb-portfolio-slider-item kb-slide-item\"><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:176.8%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"884\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/barberadalbasuperiore-lucrezia.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/barberadalbasuperiore-lucrezia.png 500w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/barberadalbasuperiore-lucrezia-170x300.png 170w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/cascinadelpozzo.com\/en\/wines\/barbera-dalba-superiore-lucrezia\/\" aria-label=\"Barbera d&#8217;Alba Superiore Lucrezia\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h3 class=\"entry-title kb-portfolio-loop-title\">Barbera d&#8217;Alba Superiore Lucrezia<\/h3><\/div><\/div><\/div><\/div><\/li><li class=\"kb-portfolio-slider-item kb-slide-item\"><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:176.8%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"884\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/dolcetto.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/dolcetto.png 500w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/dolcetto-170x300.png 170w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/cascinadelpozzo.com\/en\/wines\/langhe-dolcetto\/\" aria-label=\"Langhe Dolcetto\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h3 class=\"entry-title kb-portfolio-loop-title\">Langhe Dolcetto<\/h3><\/div><\/div><\/div><\/div><\/li><li class=\"kb-portfolio-slider-item kb-slide-item\"><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:176.8%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"884\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/langherosato-larosadelpozzo.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/langherosato-larosadelpozzo.png 500w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/langherosato-larosadelpozzo-170x300.png 170w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/cascinadelpozzo.com\/en\/wines\/langhe-rosato-la-rosa-del-pozzo\/\" aria-label=\"Langhe Rosato La Rosa del Pozzo\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h3 class=\"entry-title kb-portfolio-loop-title\">Langhe Rosato La Rosa del Pozzo<\/h3><\/div><\/div><\/div><\/div><\/li><li class=\"kb-portfolio-slider-item kb-slide-item\"><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:176.8%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"884\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/langhebiancoprasoray.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/langhebiancoprasoray.png 500w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/langhebiancoprasoray-170x300.png 170w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/cascinadelpozzo.com\/en\/wines\/langhe-white-prasoray\/\" aria-label=\"Langhe White Prasoray\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h3 class=\"entry-title kb-portfolio-loop-title\">Langhe White Prasoray<\/h3><\/div><\/div><\/div><\/div><\/li><li class=\"kb-portfolio-slider-item kb-slide-item\"><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:176.8%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"884\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/yoyelanghebianco.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/yoyelanghebianco.png 500w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/yoyelanghebianco-170x300.png 170w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/cascinadelpozzo.com\/en\/wines\/langhe-bianco-io-ye\/\" aria-label=\"Langhe Bianco io-y\u00e8\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h3 class=\"entry-title kb-portfolio-loop-title\">Langhe Bianco io-y\u00e8<\/h3><\/div><\/div><\/div><\/div><\/li><li class=\"kb-portfolio-slider-item kb-slide-item\"><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:176.8%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"884\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/roeroarneismontemeraviglia.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/roeroarneismontemeraviglia.png 500w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/roeroarneismontemeraviglia-170x300.png 170w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/cascinadelpozzo.com\/en\/wines\/roero-arneis-montemeraviglia\/\" aria-label=\"Roero Arneis Montemeraviglia\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h3 class=\"entry-title kb-portfolio-loop-title\">Roero Arneis Montemeraviglia<\/h3><\/div><\/div><\/div><\/div><\/li><li class=\"kb-portfolio-slider-item kb-slide-item\"><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:176.8%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"884\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/langhefavoritalaganella.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/langhefavoritalaganella.png 500w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/langhefavoritalaganella-170x300.png 170w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/cascinadelpozzo.com\/en\/wines\/langhe-favorita-laganella\/\" aria-label=\"Langhe Favorita Laganella\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h3 class=\"entry-title kb-portfolio-loop-title\">Langhe Favorita Laganella<\/h3><\/div><\/div><\/div><\/div><\/li><li class=\"kb-portfolio-slider-item kb-slide-item\"><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:176.8%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"884\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/chapinar.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/chapinar.png 500w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/chapinar-170x300.png 170w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/cascinadelpozzo.com\/en\/wines\/chapinar\/\" aria-label=\"Chapinar\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h3 class=\"entry-title kb-portfolio-loop-title\">Chapinar<\/h3><\/div><\/div><\/div><\/div><\/li><li class=\"kb-portfolio-slider-item kb-slide-item\"><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:176.8%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"884\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/spumante-brut-decimo-rosa-cascinadelpozzo.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/spumante-brut-decimo-rosa-cascinadelpozzo.png 500w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/spumante-brut-decimo-rosa-cascinadelpozzo-170x300.png 170w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/cascinadelpozzo.com\/en\/wines\/tenth-rose\/\" aria-label=\"Tenth Rose\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h3 class=\"entry-title kb-portfolio-loop-title\">Tenth Rose<\/h3><\/div><\/div><\/div><\/div><\/li><li class=\"kb-portfolio-slider-item kb-slide-item\"><div class=\"kb-blocks-portfolio-grid-item\"><div class=\"kb-blocks-portfolio-grid-item-inner-wrap kb-feat-image-align-none\"><div class=\"kadence-portfolio-image\"><div class=\"kadence-portfolio-image-intrisic kt-image-ratio-nocrop\" style=\"padding-bottom:176.8%\"><div class=\"kadence-portfolio-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"884\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/spumante-brut-decimo-cascinadelpozzo.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/spumante-brut-decimo-cascinadelpozzo.png 500w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/spumante-brut-decimo-cascinadelpozzo-170x300.png 170w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/div><\/div><\/div><div class=\"kb-portfolio-grid-item-inner\"><a href=\"https:\/\/cascinadelpozzo.com\/en\/wines\/tenth\/\" aria-label=\"Tenth\" class=\"portfolio-hover-item-link\"><\/a><div class=\"kb-portfolio-overlay-color\"><\/div><div class=\"kb-portfolio-overlay-border\"><\/div><div class=\"kb-portfolio-content-item-inner\"><h3 class=\"entry-title kb-portfolio-loop-title\">Tenth<\/h3><\/div><\/div><\/div><\/div><\/li><\/ul><\/div><div class=\"clearfix\" style=\"clear:both\"><\/div><\/div><\/div><\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id6_c6c5b7-ef > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6_c6c5b7-ef > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6_c6c5b7-ef > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:80px;padding-right:20px;padding-bottom:80px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id6_c6c5b7-ef > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6_c6c5b7-ef > .kt-row-column-wrap{padding-top:40px;padding-right:150px;padding-bottom:60px;padding-left:150px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id6_c6c5b7-ef > .kt-row-column-wrap{padding-top:40px;padding-right:30px;padding-bottom:40px;padding-left:30px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6_c6c5b7-ef alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column6_8d0e1d-85 > .kt-inside-inner-col,.kadence-column6_8d0e1d-85 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6_8d0e1d-85 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6_8d0e1d-85 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6_8d0e1d-85 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6_8d0e1d-85 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6_8d0e1d-85{position:relative;}@media all and (max-width: 1024px){.kadence-column6_8d0e1d-85 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6_8d0e1d-85 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6_8d0e1d-85 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id6_b63749-af > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6_b63749-af > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6_b63749-af > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:600px;margin-left:auto;margin-right:auto;padding-top:0px;padding-bottom:25px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id6_b63749-af > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6_b63749-af > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id6_b63749-af > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6_b63749-af alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column6_2885ae-55 > .kt-inside-inner-col,.kadence-column6_2885ae-55 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6_2885ae-55 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6_2885ae-55 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6_2885ae-55 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6_2885ae-55 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6_2885ae-55{position:relative;}@media all and (max-width: 1024px){.kadence-column6_2885ae-55 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6_2885ae-55 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6_2885ae-55 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id6_b71375-9d > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id6_b71375-9d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id6_b71375-9d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-sm, 1rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:25px;padding-bottom:0px;}.kb-row-layout-id6_b71375-9d > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id6_b71375-9d > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id6_b71375-9d > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6_b71375-9d > .kt-row-column-wrap{padding-top:0px;grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id6_b71375-9d > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 767px){.kb-row-layout-id6_b71375-9d > .kt-row-column-wrap{padding-top:0px;grid-template-columns:minmax(0, 1fr) minmax(0, 2fr) minmax(0, 1fr);}.kb-row-layout-id6_b71375-9d > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6_b71375-9d alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-center-half kt-row-valign-middle\">\n<style>.kadence-column6_a8e0b2-e7 > .kt-inside-inner-col{display:flex;}.kadence-column6_a8e0b2-e7 > .kt-inside-inner-col,.kadence-column6_a8e0b2-e7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6_a8e0b2-e7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6_a8e0b2-e7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column6_a8e0b2-e7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column6_a8e0b2-e7{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_a8e0b2-e7{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_a8e0b2-e7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column6_a8e0b2-e7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6_a8e0b2-e7{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column6_a8e0b2-e7{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_a8e0b2-e7{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_a8e0b2-e7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column6_a8e0b2-e7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column6_a8e0b2-e7{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_a8e0b2-e7{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_a8e0b2-e7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column6_a8e0b2-e7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6_a8e0b2-e7 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-6_3ef178-12 .kt-divider{border-top-width:1px;height:1px;border-top-color:var(--global-palette6, #718096);width:40%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-6_3ef178-12 alignnone\"><div class=\"kt-block-spacer kt-block-spacer-halign-right\"><hr class=\"kt-divider\"\/><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column6_b579fa-53 > .kt-inside-inner-col{display:flex;}.kadence-column6_b579fa-53 > .kt-inside-inner-col,.kadence-column6_b579fa-53 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6_b579fa-53 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6_b579fa-53 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column6_b579fa-53 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column6_b579fa-53{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_b579fa-53{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_b579fa-53 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column6_b579fa-53 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6_b579fa-53{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column6_b579fa-53{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_b579fa-53{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_b579fa-53 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column6_b579fa-53 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column6_b579fa-53{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_b579fa-53{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_b579fa-53 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column6_b579fa-53 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6_b579fa-53 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading6_2d0ec3-4a, .wp-block-kadence-advancedheading.kt-adv-heading6_2d0ec3-4a[data-kb-block=\"kb-adv-heading6_2d0ec3-4a\"]{padding-top:0px;margin-top:0px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading6_2d0ec3-4a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading6_2d0ec3-4a[data-kb-block=\"kb-adv-heading6_2d0ec3-4a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading6_2d0ec3-4a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading6_2d0ec3-4a[data-kb-block=\"kb-adv-heading6_2d0ec3-4a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading6_2d0ec3-4a wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6_2d0ec3-4a\">ROUTES<\/h6>\n<\/div><\/div>\n\n\n<style>.kadence-column6_ed0117-22 > .kt-inside-inner-col,.kadence-column6_ed0117-22 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6_ed0117-22 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6_ed0117-22 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6_ed0117-22 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6_ed0117-22 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6_ed0117-22{position:relative;}@media all and (max-width: 1024px){.kadence-column6_ed0117-22 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6_ed0117-22 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6_ed0117-22 inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-6_22480e-56 .kt-divider{border-top-width:1px;height:1px;border-top-color:var(--global-palette6, #718096);width:40%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-6_22480e-56 alignnone\"><div class=\"kt-block-spacer kt-block-spacer-halign-left\"><hr class=\"kt-divider\"\/><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading6_e4a39c-75, .wp-block-kadence-advancedheading.kt-adv-heading6_e4a39c-75[data-kb-block=\"kb-adv-heading6_e4a39c-75\"]{margin-top:0px;text-align:center;font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading6_e4a39c-75 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading6_e4a39c-75[data-kb-block=\"kb-adv-heading6_e4a39c-75\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading6_e4a39c-75 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading6_e4a39c-75[data-kb-block=\"kb-adv-heading6_e4a39c-75\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading6_e4a39c-75 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6_e4a39c-75\">A rural reality in the heart of the Roero<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading6_f9f85c-d9, .wp-block-kadence-advancedheading.kt-adv-heading6_f9f85c-d9[data-kb-block=\"kb-adv-heading6_f9f85c-d9\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading6_f9f85c-d9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading6_f9f85c-d9[data-kb-block=\"kb-adv-heading6_f9f85c-d9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading6_f9f85c-d9 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading6_f9f85c-d9[data-kb-block=\"kb-adv-heading6_f9f85c-d9\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading6_f9f85c-d9 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6_f9f85c-d9\">In our bottles you find our commitment, our passion, our time, our promises. In Cascina del Pozzo bottles you find our family and its values.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id6_f4c703-31 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6_f4c703-31 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6_f4c703-31 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:25px;padding-right:20px;padding-bottom:60px;padding-left:20px;}.kb-row-layout-id6_f4c703-31 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id6_f4c703-31 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id6_f4c703-31 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6_f4c703-31 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id6_f4c703-31 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id6_f4c703-31 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id6_f4c703-31 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6_f4c703-31 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column6_dfef89-f0 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column6_dfef89-f0 > .kt-inside-inner-col,.kadence-column6_dfef89-f0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6_dfef89-f0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6_dfef89-f0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6_dfef89-f0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6_dfef89-f0 > .kt-inside-inner-col{background-color:var(--global-palette8, #F7FAFC);}.kadence-column6_dfef89-f0:hover > .kt-inside-inner-col{background-color:var(--global-palette7, #EDF2F7);background-image:none;}.kadence-column6_dfef89-f0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6_dfef89-f0{position:relative;}@media all and (max-width: 1024px){.kadence-column6_dfef89-f0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6_dfef89-f0 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);border-top:2px dotted var(--global-palette2, #2B6CB0);border-right:2px dotted var(--global-palette2, #2B6CB0);border-bottom:2px dotted var(--global-palette2, #2B6CB0);border-left:2px dotted var(--global-palette2, #2B6CB0);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6_dfef89-f0 kb-section-has-link inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.kb-image6_a45651-cd.kb-image-is-ratio-size, .kb-image6_a45651-cd .kb-image-is-ratio-size{max-width:240px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image6_a45651-cd.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image6_a45651-cd .kb-image-is-ratio-size{align-self:unset;}.kb-image6_a45651-cd figure{max-width:240px;}.kb-image6_a45651-cd .image-is-svg, .kb-image6_a45651-cd .image-is-svg img{width:100%;}.kb-image6_a45651-cd .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kb-image6_a45651-cd img.kb-img, .kb-image6_a45651-cd .kb-img img{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}@media all and (max-width: 1024px){.wp-block-kadence-image.kb-image6_a45651-cd:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}}@media all and (max-width: 1024px){.kb-image6_a45651-cd:not(.kb-image-is-ratio-size) .kb-img, .kb-image6_a45651-cd.kb-image-is-ratio-size{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}}@media all and (max-width: 767px){.wp-block-kadence-image.kb-image6_a45651-cd:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-top:var(--global-kb-spacing-xxs, 0.5rem);}.kb-image6_a45651-cd .kb-image-has-overlay:after{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kb-image6_a45651-cd img.kb-img, .kb-image6_a45651-cd .kb-img img{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}}<\/style>\n<div class=\"wp-block-kadence-image kb-image6_a45651-cd\"><figure class=\"aligncenter size-full kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-square\"><img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"629\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/bottiglie-cascinadelpozzo.jpg\" alt=\"\" class=\"kb-img wp-image-1551\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/bottiglie-cascinadelpozzo.jpg 605w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/bottiglie-cascinadelpozzo-600x624.jpg 600w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/bottiglie-cascinadelpozzo-289x300.jpg 289w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/><\/div><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading6_c8e98b-7a, .wp-block-kadence-advancedheading.kt-adv-heading6_c8e98b-7a[data-kb-block=\"kb-adv-heading6_c8e98b-7a\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading6_c8e98b-7a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading6_c8e98b-7a[data-kb-block=\"kb-adv-heading6_c8e98b-7a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading6_c8e98b-7a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading6_c8e98b-7a[data-kb-block=\"kb-adv-heading6_c8e98b-7a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading6_c8e98b-7a, .wp-block-kadence-advancedheading.kt-adv-heading6_c8e98b-7a[data-kb-block=\"kb-adv-heading6_c8e98b-7a\"]{margin-top:var(--global-kb-spacing-xxs, 0.5rem);margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);}}<\/style>\n<h4 class=\"kt-adv-heading6_c8e98b-7a wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6_c8e98b-7a\">Wines<\/h4>\n<\/div><a href=\"https:\/\/cascinadelpozzo.com\/vini\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n\n<style>.kadence-column6_0de59c-76 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column6_0de59c-76 > .kt-inside-inner-col,.kadence-column6_0de59c-76 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6_0de59c-76 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6_0de59c-76 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6_0de59c-76 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6_0de59c-76 > .kt-inside-inner-col{background-color:var(--global-palette8, #F7FAFC);}.kadence-column6_0de59c-76:hover > .kt-inside-inner-col{background-color:var(--global-palette7, #EDF2F7);background-image:none;}.kadence-column6_0de59c-76 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6_0de59c-76{position:relative;}@media all and (max-width: 1024px){.kadence-column6_0de59c-76 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6_0de59c-76 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);border-top:2px dotted var(--global-palette2, #2B6CB0);border-right:2px dotted var(--global-palette2, #2B6CB0);border-bottom:2px dotted var(--global-palette2, #2B6CB0);border-left:2px dotted var(--global-palette2, #2B6CB0);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6_0de59c-76 kb-section-has-link inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.kb-image6_a85f4d-45.kb-image-is-ratio-size, .kb-image6_a85f4d-45 .kb-image-is-ratio-size{max-width:240px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image6_a85f4d-45.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image6_a85f4d-45 .kb-image-is-ratio-size{align-self:unset;}.kb-image6_a85f4d-45 figure{max-width:240px;}.kb-image6_a85f4d-45 .image-is-svg, .kb-image6_a85f4d-45 .image-is-svg img{width:100%;}.kb-image6_a85f4d-45 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kb-image6_a85f4d-45 img.kb-img, .kb-image6_a85f4d-45 .kb-img img{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}@media all and (max-width: 767px){.wp-block-kadence-image.kb-image6_a85f4d-45:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-top:var(--global-kb-spacing-xxs, 0.5rem);}.kb-image6_a85f4d-45 .kb-image-has-overlay:after{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kb-image6_a85f4d-45 img.kb-img, .kb-image6_a85f4d-45 .kb-img img{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}}<\/style>\n<div class=\"wp-block-kadence-image kb-image6_a85f4d-45\"><figure class=\"aligncenter size-full kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-square\"><img loading=\"lazy\" decoding=\"async\" width=\"585\" height=\"533\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/famigliamarchisio-tralevigne-castellinaldo-alba-cn.jpg\" alt=\"\" class=\"kb-img wp-image-1554\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/famigliamarchisio-tralevigne-castellinaldo-alba-cn.jpg 585w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/famigliamarchisio-tralevigne-castellinaldo-alba-cn-300x273.jpg 300w\" sizes=\"auto, (max-width: 585px) 100vw, 585px\" \/><\/div><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading6_3c2d28-d0, .wp-block-kadence-advancedheading.kt-adv-heading6_3c2d28-d0[data-kb-block=\"kb-adv-heading6_3c2d28-d0\"]{text-align:center;font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading6_3c2d28-d0 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading6_3c2d28-d0[data-kb-block=\"kb-adv-heading6_3c2d28-d0\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading6_3c2d28-d0 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading6_3c2d28-d0[data-kb-block=\"kb-adv-heading6_3c2d28-d0\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading6_3c2d28-d0, .wp-block-kadence-advancedheading.kt-adv-heading6_3c2d28-d0[data-kb-block=\"kb-adv-heading6_3c2d28-d0\"]{margin-top:var(--global-kb-spacing-xxs, 0.5rem);margin-bottom:var(--global-kb-spacing-xs, 1rem);}}<\/style>\n<h4 class=\"kt-adv-heading6_3c2d28-d0 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6_3c2d28-d0\">Stop by and see us<\/h4>\n<\/div><a href=\"https:\/\/cascinadelpozzo.com\/vini\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n\n<style>.kadence-column6_886c4f-67 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kadence-column6_886c4f-67 > .kt-inside-inner-col,.kadence-column6_886c4f-67 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6_886c4f-67 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6_886c4f-67 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6_886c4f-67 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6_886c4f-67 > .kt-inside-inner-col{background-color:var(--global-palette8, #F7FAFC);}.kadence-column6_886c4f-67:hover > .kt-inside-inner-col{background-color:var(--global-palette7, #EDF2F7);background-image:none;}.kadence-column6_886c4f-67 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6_886c4f-67{position:relative;}@media all and (max-width: 1024px){.kadence-column6_886c4f-67 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6_886c4f-67 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);border-top:2px dotted var(--global-palette2, #2B6CB0);border-right:2px dotted var(--global-palette2, #2B6CB0);border-bottom:2px dotted var(--global-palette2, #2B6CB0);border-left:2px dotted var(--global-palette2, #2B6CB0);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6_886c4f-67 kb-section-has-link inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.kb-image6_098331-e5.kb-image-is-ratio-size, .kb-image6_098331-e5 .kb-image-is-ratio-size{max-width:240px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image6_098331-e5.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image6_098331-e5 .kb-image-is-ratio-size{align-self:unset;}.kb-image6_098331-e5 figure{max-width:240px;}.kb-image6_098331-e5 .image-is-svg, .kb-image6_098331-e5 .image-is-svg img{width:100%;}.kb-image6_098331-e5 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kb-image6_098331-e5 img.kb-img, .kb-image6_098331-e5 .kb-img img{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}@media all and (max-width: 767px){.wp-block-kadence-image.kb-image6_098331-e5:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-top:var(--global-kb-spacing-xxs, 0.5rem);}.kb-image6_098331-e5 .kb-image-has-overlay:after{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kb-image6_098331-e5 img.kb-img, .kb-image6_098331-e5 .kb-img img{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}}<\/style>\n<div class=\"wp-block-kadence-image kb-image6_098331-e5\"><figure class=\"aligncenter size-full kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-square\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"606\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/lorenzomarchisio-1.jpg\" alt=\"\" class=\"kb-img wp-image-1556\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/lorenzomarchisio-1.jpg 512w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/lorenzomarchisio-1-253x300.jpg 253w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/div><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading6_9b26db-22, .wp-block-kadence-advancedheading.kt-adv-heading6_9b26db-22[data-kb-block=\"kb-adv-heading6_9b26db-22\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading6_9b26db-22 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading6_9b26db-22[data-kb-block=\"kb-adv-heading6_9b26db-22\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading6_9b26db-22 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading6_9b26db-22[data-kb-block=\"kb-adv-heading6_9b26db-22\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading6_9b26db-22, .wp-block-kadence-advancedheading.kt-adv-heading6_9b26db-22[data-kb-block=\"kb-adv-heading6_9b26db-22\"]{margin-top:var(--global-kb-spacing-xxs, 0.5rem);margin-bottom:var(--global-kb-spacing-xs, 1rem);}}<\/style>\n<h4 class=\"kt-adv-heading6_9b26db-22 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6_9b26db-22\">Contact us<a href=\"#\"><\/a><\/h4>\n<\/div><a href=\"https:\/\/cascinadelpozzo.com\/vini\/\" class=\"kb-section-link-overlay\"><\/a><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id6_dffb27-f5 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id6_dffb27-f5 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id6_dffb27-f5 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-sm, 1rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:120px;padding-right:20px;padding-bottom:80px;padding-left:20px;}.kb-row-layout-id6_dffb27-f5 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id6_dffb27-f5 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id6_dffb27-f5 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6_dffb27-f5 > .kt-row-column-wrap{padding-top:120px;padding-right:150px;padding-bottom:60px;padding-left:150px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id6_dffb27-f5 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 767px){.kb-row-layout-id6_dffb27-f5 > .kt-row-column-wrap{padding-top:100px;padding-right:30px;padding-bottom:40px;padding-left:30px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id6_dffb27-f5 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6_dffb27-f5 alignnone has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column6_77e1d7-80 > .kt-inside-inner-col,.kadence-column6_77e1d7-80 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6_77e1d7-80 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6_77e1d7-80 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6_77e1d7-80 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6_77e1d7-80 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6_77e1d7-80{position:relative;}@media all and (max-width: 1024px){.kadence-column6_77e1d7-80 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6_77e1d7-80 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6_77e1d7-80 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id6_dab220-67{margin-top:-80px;}.kb-row-layout-id6_dab220-67 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id6_dab220-67 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id6_dab220-67 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-sm, 1rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:5px;grid-template-columns:minmax(0, calc(40% - ((var(--global-kb-gap-sm, 1rem) * 1 )\/2)))minmax(0, calc(60% - ((var(--global-kb-gap-sm, 1rem) * 1 )\/2)));}.kb-row-layout-id6_dab220-67 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id6_dab220-67 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id6_dab220-67 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id6_dab220-67 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-equal kt-row-valign-middle\">\n<style>.kadence-column6_88cc0f-46 > .kt-inside-inner-col{display:flex;}.kadence-column6_88cc0f-46 > .kt-inside-inner-col,.kadence-column6_88cc0f-46 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6_88cc0f-46 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6_88cc0f-46 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column6_88cc0f-46 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column6_88cc0f-46{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_88cc0f-46{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_88cc0f-46 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column6_88cc0f-46 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6_88cc0f-46{z-index:200;position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column6_88cc0f-46{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_88cc0f-46{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_88cc0f-46 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column6_88cc0f-46 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column6_88cc0f-46{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_88cc0f-46{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_88cc0f-46 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column6_88cc0f-46 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6_88cc0f-46 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading6_80ebf4-bc, .wp-block-kadence-advancedheading.kt-adv-heading6_80ebf4-bc[data-kb-block=\"kb-adv-heading6_80ebf4-bc\"]{padding-top:0px;margin-top:0px;text-align:left;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading6_80ebf4-bc mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading6_80ebf4-bc[data-kb-block=\"kb-adv-heading6_80ebf4-bc\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading6_80ebf4-bc img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading6_80ebf4-bc[data-kb-block=\"kb-adv-heading6_80ebf4-bc\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading6_80ebf4-bc wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading6_80ebf4-bc\">Do you have a club?<\/h6>\n<\/div><\/div>\n\n\n<style>.kadence-column6_465008-d0 > .kt-inside-inner-col{display:flex;}.kadence-column6_465008-d0 > .kt-inside-inner-col,.kadence-column6_465008-d0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6_465008-d0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6_465008-d0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column6_465008-d0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column6_465008-d0{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_465008-d0{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_465008-d0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column6_465008-d0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6_465008-d0{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column6_465008-d0{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_465008-d0{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_465008-d0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column6_465008-d0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column6_465008-d0{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_465008-d0{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column6_465008-d0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column6_465008-d0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6_465008-d0 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-6_c67bc8-31 .kt-divider{border-top-width:1px;height:1px;border-top-color:var(--global-palette6, #718096);width:30%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-6_c67bc8-31 alignnone\"><div class=\"kt-block-spacer kt-block-spacer-halign-left\"><hr class=\"kt-divider\"\/><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading6_1f8517-1b, .wp-block-kadence-advancedheading.kt-adv-heading6_1f8517-1b[data-kb-block=\"kb-adv-heading6_1f8517-1b\"]{margin-top:-10px;margin-right:50px;font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading6_1f8517-1b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading6_1f8517-1b[data-kb-block=\"kb-adv-heading6_1f8517-1b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading6_1f8517-1b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading6_1f8517-1b[data-kb-block=\"kb-adv-heading6_1f8517-1b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading6_1f8517-1b, .wp-block-kadence-advancedheading.kt-adv-heading6_1f8517-1b[data-kb-block=\"kb-adv-heading6_1f8517-1b\"]{margin-right:0px;margin-left:0px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading6_1f8517-1b, .wp-block-kadence-advancedheading.kt-adv-heading6_1f8517-1b[data-kb-block=\"kb-adv-heading6_1f8517-1b\"]{margin-right:0px;margin-left:0px;font-size:var(--global-kb-font-size-lg, 2rem);}}<\/style>\n<h2 class=\"kt-adv-heading6_1f8517-1b wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6_1f8517-1b\">Wine shops, restaurants, accommodations, bars and pubs, events and demonstrations.<\/h2>\n<\/div><\/div>\n\n\n<style>.kadence-column6_fb9315-3d > .kt-inside-inner-col,.kadence-column6_fb9315-3d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6_fb9315-3d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6_fb9315-3d > .kt-inside-inner-col{flex-direction:column;}.kadence-column6_fb9315-3d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6_fb9315-3d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6_fb9315-3d{z-index:-200;position:relative;}@media all and (max-width: 1024px){.kadence-column6_fb9315-3d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column6_fb9315-3d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6_fb9315-3d inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image6_02eb42-f9{position:relative;z-index:-200;}.kb-image6_02eb42-f9 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image6_02eb42-f9 size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"770\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/ristorante-con-vini-cascinadelpozzo.jpg\" alt=\"\" class=\"kb-img wp-image-1560\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/ristorante-con-vini-cascinadelpozzo.jpg 721w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/ristorante-con-vini-cascinadelpozzo-600x641.jpg 600w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/ristorante-con-vini-cascinadelpozzo-281x300.jpg 281w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column6_ca1cf6-00 > .kt-inside-inner-col,.kadence-column6_ca1cf6-00 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column6_ca1cf6-00 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column6_ca1cf6-00 > .kt-inside-inner-col{flex-direction:column;}.kadence-column6_ca1cf6-00 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column6_ca1cf6-00 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column6_ca1cf6-00{position:relative;}.kadence-column6_ca1cf6-00, .kt-inside-inner-col > .kadence-column6_ca1cf6-00:not(.specificity){margin-left:60px;}@media all and (max-width: 1024px){.kadence-column6_ca1cf6-00 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column6_ca1cf6-00, .kt-inside-inner-col > .kadence-column6_ca1cf6-00:not(.specificity){margin-right:0px;margin-left:0px;}}@media all and (max-width: 767px){.kadence-column6_ca1cf6-00{text-align:center;}.kadence-column6_ca1cf6-00 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column6_ca1cf6-00, .kt-inside-inner-col > .kadence-column6_ca1cf6-00:not(.specificity){margin-right:0px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column6_ca1cf6-00 inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading6_a346c3-5e, .wp-block-kadence-advancedheading.kt-adv-heading6_a346c3-5e[data-kb-block=\"kb-adv-heading6_a346c3-5e\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading6_a346c3-5e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading6_a346c3-5e[data-kb-block=\"kb-adv-heading6_a346c3-5e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading6_a346c3-5e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading6_a346c3-5e[data-kb-block=\"kb-adv-heading6_a346c3-5e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading6_a346c3-5e wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading6_a346c3-5e\">Would you like to introduce one or more <strong>Cascina del Pozzo<\/strong> bottles to your venue? Contact us and we will visit you to find the right labels for your type of facility.<\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns6_6c67ff-75{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns6_6c67ff-75 .kt-button{font-weight:normal;font-style:normal;}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn.kb-btns6_6c67ff-75{justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns6_6c67ff-75\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn6_04aeaa-8e.kb-button{width:initial;}<\/style><a class=\"kb-button kt-button button kb-btn6_04aeaa-8e kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"https:\/\/cascinadelpozzo.com\/en\/contact\/\"><span class=\"kt-btn-inner-text\">CONTACTS<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id1516_7eea98-6d > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1516_7eea98-6d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1516_7eea98-6d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-right:0px;padding-bottom:20px;padding-left:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1516_7eea98-6d > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1516_7eea98-6d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1516_7eea98-6d > .kt-row-column-wrap{padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1516_7eea98-6d alignnone has-theme-palette7-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1516_0ab8e4-10 > .kt-inside-inner-col{padding-top:60px;padding-right:50px;padding-bottom:60px;padding-left:50px;}.kadence-column1516_0ab8e4-10 > .kt-inside-inner-col,.kadence-column1516_0ab8e4-10 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1516_0ab8e4-10 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1516_0ab8e4-10 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1516_0ab8e4-10 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1516_0ab8e4-10 > .kt-inside-inner-col{background-color:var(--global-palette7, #EDF2F7);}.kadence-column1516_0ab8e4-10 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1516_0ab8e4-10{position:relative;}.kadence-column1516_0ab8e4-10, .kt-inside-inner-col > .kadence-column1516_0ab8e4-10:not(.specificity){margin-right:20px;}@media all and (max-width: 1024px){.kadence-column1516_0ab8e4-10 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1516_0ab8e4-10, .kt-inside-inner-col > .kadence-column1516_0ab8e4-10:not(.specificity){margin-right:0px;margin-left:0px;}}@media all and (max-width: 767px){.kadence-column1516_0ab8e4-10 > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;flex-direction:column;justify-content:center;}.kadence-column1516_0ab8e4-10, .kt-inside-inner-col > .kadence-column1516_0ab8e4-10:not(.specificity){margin-right:0px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1516_0ab8e4-10 inner-column-1\"><div class=\"kt-inside-inner-col\"><pre class=\"ti-widget\"><template id=\"trustindex-google-widget-html\"><div class=\" ti-widget  ti-goog ti-review-text-mode-readmore ti-text-align-left\" data-no-translation=\"true\" data-time-locale=\"%d %s fa|oggi|giorno|giorni|settimana|settimane|mese|mesi|anno|anni\" data-plugin-version=\"13.2.9\" data-layout-id=\"34\" data-layout-category=\"slider\" data-set-id=\"light-background\" data-pid=\"\" data-language=\"it\" data-close-locale=\"Vicino\" data-review-target-width=\"300\" data-css-version=\"2\" data-reply-by-locale=\"Risposta dal proprietario\" data-only-rating-locale=\"Questo utente ha lasciato solo una valutazione.\" data-pager-autoplay-timeout=\"6\"> <div class=\"ti-widget-container ti-col-3\"> <div class=\"ti-header ti-header-grid source-Google\"> <div class=\"ti-fade-container\"> <div class=\"ti-rating-text\"> <strong class=\"ti-rating ti-rating-large\"> ECCELLENTE <\/strong> <\/div> <span class=\"ti-stars star-lg\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-rating-text\"> <span class=\"nowrap\">In base a <strong>83 recensioni<\/strong><\/span> <\/div> <div class=\"ti-large-logo\"> <div class=\"ti-v-center\"> <trustindex-image class=\"ti-logo-fb\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/logo.svg\" width=\"150\" height=\"25\" loading=\"lazy\" alt=\"Google\"><\/trustindex-image> <\/div> <\/div> <\/div> <\/div> <div class=\"ti-reviews-container\"> <div class=\"ti-controls\"> <div class=\"ti-next\" aria-label=\"Prossima recensione\" role=\"button\" tabindex=\"0\"><\/div> <div class=\"ti-prev\" aria-label=\"Recensione precedente\" role=\"button\" tabindex=\"0\"><\/div> <\/div> <div class=\"ti-reviews-container-wrapper\">  <div data-empty=\"0\" data-time=\"1696723200\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Pubblicato su Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJDfnKsiER4yF3ehuqM-fTPRHdVIOn5K9xZZMX4Gz0c=w40-h40-c-rp-mo-br100\" alt=\"Francesca Whalen profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Francesca Whalen <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica che la fonte originale della recensione sia Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->I had the pleasure of trying the family wines at the Truffle festival. The hosts were very kind and the wine was excellent especially the Roero Riserva. Excellent wine at an excellent price!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Nascondere\" data-open-text=\"Leggi di pi\u00f9\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1690329600\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Pubblicato su Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjVEbt_ql2jsanSN3Dfi6vrH_jJugRqrjLGVqB0gxCd4jsc=w40-h40-c-rp-mo-br100\" alt=\"Marc Leemans profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Marc Leemans <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica che la fonte originale della recensione sia Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->What a wonderfull discovery ! Visit this winery, you will not be dissapointed. Family run, some of the most excellent Roero wines. All for reasonable\/affordable prices. The family is so nice and take their time to give all the information you need. Tasting was free and without reservation. Alot of respect and gratefull thank you to Lorenzo for guiding us, regard to all the family from myself and my wife. When we return to the region next year, we\u2019ll definately re-visit !<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Nascondere\" data-open-text=\"Leggi di pi\u00f9\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1689724800\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Pubblicato su Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjX6x2sy1ZT9SAfz1xxhDDD37FU2q7ouUtkJvZ_zvPBvDg=w40-h40-c-rp-mo-br100\" alt=\"tymon ferenc de laat profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> tymon ferenc de laat <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica che la fonte originale della recensione sia Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->After visiting several vineyards and ( sometimes over priced) winetastings around the Langhe area we accidentally stumbled across the winery Cascina del Pozzo. What a refreshing and welcoming experience. Gabriel took the time to explain   his methods and let us taste over 9 wines free of charge. The Favorita and Chardonnay 2016 were abslotule winners aswell as their Barbaresco. A must visit if you would like to meet a real passionate and well balanced winemaker. We will come back here one day for sure.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Nascondere\" data-open-text=\"Leggi di pi\u00f9\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1689465600\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Pubblicato su Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjUeJ47VjYQOiyZJ653iMLfV8ma0mOYFQtSyZ0DnFq_x2fc=w40-h40-c-rp-mo-ba2-br100\" alt=\"maurizio sacco profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> maurizio sacco <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica che la fonte originale della recensione sia Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Dove la tradizione e l'eccellenza si incontrano in una location incantevole, il tutto accompagnato dalla simpatica e piacevole compagnia dei proprietari che sanno metterti a proprio agio in maniera naturale. Ma se per caso non ci riuscissero  sicuramente i loro vini  colmerebbero ogni tipo di richiesta.  La prova del nove dopo averne bevuti in quantit\u00e0 il risveglio senza mal di testa a confermare la naturalezza dei vini<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Nascondere\" data-open-text=\"Leggi di pi\u00f9\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1684540800\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Pubblicato su Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocIHTKpaYgKzY3XjXeBsau1JPbzHv9TLoPhOh0Wwydi_=w40-h40-c-rp-mo-br100\" alt=\"Eddy \u201cEdso\u201d profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Eddy \u201cEdso\u201d <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica che la fonte originale della recensione sia Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Super sympathieke ontvangst.  Lekkere wijndegustatie met bijhorend hapjes \u00e9n het verhaal van deze familie en hun topwijnen. Dank Lorenzo, en zeker tot ziens! Ciao<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Nascondere\" data-open-text=\"Leggi di pi\u00f9\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1660867200\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Pubblicato su Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocIDl-nL02n1Ss6sHUexBDMAG0A0peajoByilCe3yJ0f=w40-h40-c-rp-mo-br100\" alt=\"Jeroen Huijg profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Jeroen Huijg <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica che la fonte originale della recensione sia Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Very friendly people at this family winery! We just wanted to buy some wine at a random local winery, we came here unannounced and they immediately prepared an extensive tasting for us. A lot of different nice (and reasonably priced) wines!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Nascondere\" data-open-text=\"Leggi di pi\u00f9\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1616371200\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Pubblicato su Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjV64gXHavezBRHe8_AvTSB0WLgjYcOR59s0QjvraPA4QfU=w40-h40-c-rp-mo-ba6-br100\" alt=\"Gianluca Morino profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Gianluca Morino <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica che la fonte originale della recensione sia Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Amazing wines and cellar<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Nascondere\" data-open-text=\"Leggi di pi\u00f9\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1525132800\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\" data-language=\"\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Pubblicato su Google<\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"Google\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJ8B-NAlFHl--1YOgbemKmcQ0Qnsj9INx8VI95gqGIv=w40-h40-c-rp-mo-br100\" alt=\"Robert Wahlen profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Robert Wahlen <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 1\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 2\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 3\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 4\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google star 5\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica che la fonte originale della recensione sia Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Were nice vineyard, great hospitality, wine tasting and excellent wines. We had a great time when we were visiting Cascina del Pozza and are now looking forward to try the wines at home.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Nascondere\" data-open-text=\"Leggi di pi\u00f9\"><\/span> <\/div> <\/div>  <\/div> <div class=\"ti-controls-line\"> <div class=\"dot\"><\/div> <\/div> <\/div>   <\/div> <\/div> <\/template><\/pre><div data-src=\"https:\/\/cdn.trustindex.io\/loader.js?wp-widget\" data-template-id=\"trustindex-google-widget-html\" data-css-url=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/trustindex-google-widget.css?1774210061\"><\/div>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>UN BENVENUTO DALLA FAMIGLIA MARCHISIO Winemakers in the Roero for five generations Since the early 1900s, the Marchisio Family has worked together with the land of Castellinaldo to produce wine at the Pozzo vineyard. It is from here that Cascina del Pozzo takes its name. Wines Discover our wines ROUTES A rural reality in the&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"hide","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-2324","page","type-page","status-publish","hentry"],"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"admin","author_link":"https:\/\/cascinadelpozzo.com\/en\/author\/admin\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/cascinadelpozzo.com\/en\/wp-json\/wp\/v2\/pages\/2324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cascinadelpozzo.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cascinadelpozzo.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cascinadelpozzo.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cascinadelpozzo.com\/en\/wp-json\/wp\/v2\/comments?post=2324"}],"version-history":[{"count":3,"href":"https:\/\/cascinadelpozzo.com\/en\/wp-json\/wp\/v2\/pages\/2324\/revisions"}],"predecessor-version":[{"id":2650,"href":"https:\/\/cascinadelpozzo.com\/en\/wp-json\/wp\/v2\/pages\/2324\/revisions\/2650"}],"wp:attachment":[{"href":"https:\/\/cascinadelpozzo.com\/en\/wp-json\/wp\/v2\/media?parent=2324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}