{"id":2355,"date":"2023-11-11T18:09:16","date_gmt":"2023-11-11T18:09:16","guid":{"rendered":"https:\/\/cascinadelpozzo.com\/wines\/roero-riserva-serra-zoanni\/"},"modified":"2024-08-18T08:04:13","modified_gmt":"2024-08-18T08:04:13","slug":"roero-riserva-serra-zoanni","status":"publish","type":"page","link":"https:\/\/cascinadelpozzo.com\/en\/wines\/roero-riserva-serra-zoanni\/","title":{"rendered":"Roero Riserva Serra Zoanni"},"content":{"rendered":"<style>.kb-row-layout-id1117_377e43-c6 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1117_377e43-c6 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1117_377e43-c6 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1117_377e43-c6{background-image:url('https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/09\/uva-vite.cascinadelpozzo.jpg');background-size:cover;background-position:57.99999999999999% 74%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id1117_377e43-c6 > .kt-row-layout-overlay{opacity:0.69;background-color:var(--global-palette9, #ffffff);}@media all and (max-width: 1024px){.kb-row-layout-id1117_377e43-c6 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1117_377e43-c6 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1117_377e43-c6 alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1117_52298c-9d > .kt-inside-inner-col,.kadence-column1117_52298c-9d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1117_52298c-9d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1117_52298c-9d > .kt-inside-inner-col{flex-direction:column;}.kadence-column1117_52298c-9d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1117_52298c-9d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1117_52298c-9d{position:relative;}@media all and (max-width: 1024px){.kadence-column1117_52298c-9d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1117_52298c-9d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1117_52298c-9d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-1117_59dffd-af .kt-block-spacer{height:100px;}.wp-block-kadence-spacer.kt-block-spacer-1117_59dffd-af .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-1117_59dffd-af\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1117_8249c4-ad, .wp-block-kadence-advancedheading.kt-adv-heading1117_8249c4-ad[data-kb-block=\"kb-adv-heading1117_8249c4-ad\"]{text-align:center;font-style:normal;color:#1d1d1b;}.wp-block-kadence-advancedheading.kt-adv-heading1117_8249c4-ad mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1117_8249c4-ad[data-kb-block=\"kb-adv-heading1117_8249c4-ad\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1117_8249c4-ad img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1117_8249c4-ad[data-kb-block=\"kb-adv-heading1117_8249c4-ad\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h1 class=\"kt-adv-heading1117_8249c4-ad wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1117_8249c4-ad\">Roero Riserva<\/h1>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1117_826e82-fb, .wp-block-kadence-advancedheading.kt-adv-heading1117_826e82-fb[data-kb-block=\"kb-adv-heading1117_826e82-fb\"]{text-align:center;font-style:normal;color:#1d1d1b;text-shadow:9px 1px 14px #f4f0c6;}.wp-block-kadence-advancedheading.kt-adv-heading1117_826e82-fb mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1117_826e82-fb[data-kb-block=\"kb-adv-heading1117_826e82-fb\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1117_826e82-fb img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1117_826e82-fb[data-kb-block=\"kb-adv-heading1117_826e82-fb\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading1117_826e82-fb, .wp-block-kadence-advancedheading.kt-adv-heading1117_826e82-fb[data-kb-block=\"kb-adv-heading1117_826e82-fb\"]{text-shadow:9px 1px 14px #f4f0c6;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1117_826e82-fb, .wp-block-kadence-advancedheading.kt-adv-heading1117_826e82-fb[data-kb-block=\"kb-adv-heading1117_826e82-fb\"]{text-shadow:9px 1px 14px #f4f0c6;}}<\/style>\n<h3 class=\"kt-adv-heading1117_826e82-fb wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1117_826e82-fb\">Serra Zoanni<\/h3>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-1117_6bcd97-c2 .kt-block-spacer{height:100px;}.wp-block-kadence-spacer.kt-block-spacer-1117_6bcd97-c2 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-1117_6bcd97-c2\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id1117_9f57e3-4d > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1117_9f57e3-4d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1117_9f57e3-4d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1117_9f57e3-4d > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1117_9f57e3-4d > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1117_9f57e3-4d > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1117_9f57e3-4d alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1117_c9db71-ea > .kt-inside-inner-col,.kadence-column1117_c9db71-ea > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1117_c9db71-ea > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1117_c9db71-ea > .kt-inside-inner-col{flex-direction:column;}.kadence-column1117_c9db71-ea > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1117_c9db71-ea > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1117_c9db71-ea{position:relative;}@media all and (max-width: 1024px){.kadence-column1117_c9db71-ea > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1117_c9db71-ea > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1117_c9db71-ea\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-1117_2c8b1a-9a .kt-block-spacer{height:40px;}.wp-block-kadence-spacer.kt-block-spacer-1117_2c8b1a-9a .kt-divider{border-top-width:4px;border-top-color:#1d1d1b;width:35%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-1117_2c8b1a-9a\"><div class=\"kt-block-spacer kt-block-spacer-halign-left\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.kb-row-layout-id1117_1dd45b-99 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1117_1dd45b-99 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1117_1dd45b-99 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1117_1dd45b-99 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1117_1dd45b-99 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1117_1dd45b-99 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1117_1dd45b-99 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1117_7973d3-11 > .kt-inside-inner-col{display:flex;}.kadence-column1117_7973d3-11 > .kt-inside-inner-col,.kadence-column1117_7973d3-11 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1117_7973d3-11 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}.kadence-column1117_7973d3-11 > .kt-inside-inner-col > *, .kadence-column1117_7973d3-11 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1117_7973d3-11 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1117_7973d3-11 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kadence-column1117_7973d3-11 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1117_7973d3-11{position:relative;}@media all and (max-width: 1024px){.kadence-column1117_7973d3-11 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column1117_7973d3-11 > .kt-inside-inner-col > *, .kadence-column1117_7973d3-11 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1117_7973d3-11 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1117_7973d3-11 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kadence-column1117_7973d3-11 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column1117_7973d3-11 > .kt-inside-inner-col > *, .kadence-column1117_7973d3-11 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1117_7973d3-11 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1117_7973d3-11 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1117_7973d3-11 kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.kt-svg-icons1117_4c5867-dc .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons1117_4c5867-dc{justify-content:center;}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons1117_4c5867-dc alignnone\"><style>.kt-svg-item-1117_d90b1d-e3 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-1117_d90b1d-e3 .kb-svg-icon-wrap{color:var(--global-palette1, #3182CE);font-size:15px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-1117_d90b1d-e3\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_info-circle\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M256 8C119.043 8 8 119.083 8 256c0 136.997 111.043 248 248 248s248-111.003 248-248C504 119.083 392.957 8 256 8zm0 110c23.196 0 42 18.804 42 42s-18.804 42-42 42-42-18.804-42-42 18.804-42 42-42zm56 254c0 6.627-5.373 12-12 12h-88c-6.627 0-12-5.373-12-12v-24c0-6.627 5.373-12 12-12h12v-64h-12c-6.627 0-12-5.373-12-12v-24c0-6.627 5.373-12 12-12h64c6.627 0 12 5.373 12 12v100h12c6.627 0 12 5.373 12 12v24z\"\/><\/svg><\/span><\/div>\n<\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1117_e8172e-25, .wp-block-kadence-advancedheading.kt-adv-heading1117_e8172e-25[data-kb-block=\"kb-adv-heading1117_e8172e-25\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1117_e8172e-25 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1117_e8172e-25[data-kb-block=\"kb-adv-heading1117_e8172e-25\"] mark.kt-highlight{font-style:normal;color:var(--global-palette1, #3182CE);-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1117_e8172e-25 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1117_e8172e-25[data-kb-block=\"kb-adv-heading1117_e8172e-25\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1117_e8172e-25 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading1117_e8172e-25\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-theme-palette-8-color\"><mark style=\"\" class=\"kt-highlight\"><strong style=\"background-color: rgba(0, 0, 0, 0);\">First vintage<\/strong>: <\/mark><\/mark><em>2017<\/em><\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1117_a6a94f-97, .wp-block-kadence-advancedheading.kt-adv-heading1117_a6a94f-97[data-kb-block=\"kb-adv-heading1117_a6a94f-97\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1117_a6a94f-97 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1117_a6a94f-97[data-kb-block=\"kb-adv-heading1117_a6a94f-97\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1117_a6a94f-97 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1117_a6a94f-97[data-kb-block=\"kb-adv-heading1117_a6a94f-97\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1117_a6a94f-97 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1117_a6a94f-97\">With the arrival of geographical mentions, we wanted to vinify separately the nebbiolo vineyard planted in the 1960s. <strong>Serra Zoanni<\/strong> comes from clay-rich soil and is distinguished from Montegalletto by its spicy and intense aromatics, but also by soft, silky and persistent tannin.  <\/p>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-1117_2e44e3-cc .kt-block-spacer{height:30px;}.wp-block-kadence-spacer.kt-block-spacer-1117_2e44e3-cc .kt-divider{border-top-width:4px;border-top-color:#1d1d1b;width:100%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-1117_2e44e3-cc\"><div class=\"kt-block-spacer kt-block-spacer-halign-left\"><hr class=\"kt-divider\"\/><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1117_d9ce1a-b7 > .kt-inside-inner-col{display:flex;}.kadence-column1117_d9ce1a-b7 > .kt-inside-inner-col,.kadence-column1117_d9ce1a-b7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1117_d9ce1a-b7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1117_d9ce1a-b7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1117_d9ce1a-b7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1117_d9ce1a-b7{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1117_d9ce1a-b7{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1117_d9ce1a-b7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1117_d9ce1a-b7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1117_d9ce1a-b7{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1117_d9ce1a-b7{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1117_d9ce1a-b7{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1117_d9ce1a-b7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1117_d9ce1a-b7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1117_d9ce1a-b7{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1117_d9ce1a-b7{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1117_d9ce1a-b7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1117_d9ce1a-b7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1117_d9ce1a-b7\"><div class=\"kt-inside-inner-col\"><style>.kb-image1117_8a92b2-e7.kb-image-is-ratio-size, .kb-image1117_8a92b2-e7 .kb-image-is-ratio-size{max-width:280px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image1117_8a92b2-e7.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image1117_8a92b2-e7 .kb-image-is-ratio-size{align-self:unset;}.kb-image1117_8a92b2-e7 figure{max-width:280px;}.kb-image1117_8a92b2-e7 .image-is-svg, .kb-image1117_8a92b2-e7 .image-is-svg img{width:100%;}.kb-image1117_8a92b2-e7 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kb-image1117_8a92b2-e7 img.kb-img, .kb-image1117_8a92b2-e7 .kb-img img{border-top:4px solid var(--global-palette7, #EDF2F7);border-right:4px solid var(--global-palette7, #EDF2F7);border-bottom:4px solid var(--global-palette7, #EDF2F7);border-left:4px solid var(--global-palette7, #EDF2F7);border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}@media all and (max-width: 1024px){.kb-image1117_8a92b2-e7 img.kb-img, .kb-image1117_8a92b2-e7 .kb-img img{border-top:4px solid var(--global-palette7, #EDF2F7);border-right:4px solid var(--global-palette7, #EDF2F7);border-bottom:4px solid var(--global-palette7, #EDF2F7);border-left:4px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.kb-image1117_8a92b2-e7 img.kb-img, .kb-image1117_8a92b2-e7 .kb-img img{border-top:4px solid var(--global-palette7, #EDF2F7);border-right:4px solid var(--global-palette7, #EDF2F7);border-bottom:4px solid var(--global-palette7, #EDF2F7);border-left:4px solid var(--global-palette7, #EDF2F7);}}<\/style>\n<div class=\"wp-block-kadence-image kb-image1117_8a92b2-e7\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/serra-zoanni-roero-riserva-576x1024.jpg\" alt=\"Serra Zoanni Roero Riserva Cascina del Pozzo\" class=\"kb-img wp-image-1118\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/serra-zoanni-roero-riserva-576x1024.jpg 576w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/serra-zoanni-roero-riserva-600x1066.jpg 600w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/serra-zoanni-roero-riserva-169x300.jpg 169w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/serra-zoanni-roero-riserva-768x1365.jpg 768w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/serra-zoanni-roero-riserva-864x1536.jpg 864w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/serra-zoanni-roero-riserva.jpg 1000w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure><\/div>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id1117_0714d5-c0 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1117_0714d5-c0 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1117_0714d5-c0 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:800px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1117_0714d5-c0 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1117_0714d5-c0 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1117_0714d5-c0 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1117_0714d5-c0 alignnone has-theme-palette7-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1117_2ea40f-4c > .kt-inside-inner-col,.kadence-column1117_2ea40f-4c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1117_2ea40f-4c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1117_2ea40f-4c > .kt-inside-inner-col{flex-direction:column;}.kadence-column1117_2ea40f-4c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1117_2ea40f-4c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1117_2ea40f-4c{position:relative;}@media all and (max-width: 1024px){.kadence-column1117_2ea40f-4c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1117_2ea40f-4c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1117_2ea40f-4c\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1117_e704e2-e4, .wp-block-kadence-advancedheading.kt-adv-heading1117_e704e2-e4[data-kb-block=\"kb-adv-heading1117_e704e2-e4\"]{text-align:center;font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading1117_e704e2-e4 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1117_e704e2-e4[data-kb-block=\"kb-adv-heading1117_e704e2-e4\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1117_e704e2-e4 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1117_e704e2-e4[data-kb-block=\"kb-adv-heading1117_e704e2-e4\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading1117_e704e2-e4 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1117_e704e2-e4\">Roero Riserva<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1117_eef9c8-e7, .wp-block-kadence-advancedheading.kt-adv-heading1117_eef9c8-e7[data-kb-block=\"kb-adv-heading1117_eef9c8-e7\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1117_eef9c8-e7 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1117_eef9c8-e7[data-kb-block=\"kb-adv-heading1117_eef9c8-e7\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1117_eef9c8-e7 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1117_eef9c8-e7[data-kb-block=\"kb-adv-heading1117_eef9c8-e7\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading1117_eef9c8-e7 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1117_eef9c8-e7\">Serra Zoanni<\/h3>\n\n\n<style>.kb-row-layout-id1117_b0f2a0-06 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1117_b0f2a0-06 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1117_b0f2a0-06 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:300px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1117_b0f2a0-06 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1117_b0f2a0-06 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1117_b0f2a0-06 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1117_b0f2a0-06 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1117_2f23ed-fd > .kt-inside-inner-col{padding-right:var(--global-kb-spacing-xl, 4rem);padding-left:var(--global-kb-spacing-xl, 4rem);}.kadence-column1117_2f23ed-fd > .kt-inside-inner-col,.kadence-column1117_2f23ed-fd > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1117_2f23ed-fd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1117_2f23ed-fd > .kt-inside-inner-col{flex-direction:column;}.kadence-column1117_2f23ed-fd > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1117_2f23ed-fd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1117_2f23ed-fd{position:relative;}@media all and (max-width: 1024px){.kadence-column1117_2f23ed-fd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1117_2f23ed-fd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1117_2f23ed-fd\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1117_2e0aba-af, .wp-block-kadence-advancedheading.kt-adv-heading1117_2e0aba-af[data-kb-block=\"kb-adv-heading1117_2e0aba-af\"]{margin-bottom:0px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1117_2e0aba-af mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1117_2e0aba-af[data-kb-block=\"kb-adv-heading1117_2e0aba-af\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1117_2e0aba-af img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1117_2e0aba-af[data-kb-block=\"kb-adv-heading1117_2e0aba-af\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1117_2e0aba-af wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1117_2e0aba-af\"><strong>Nebbiolo<\/strong><\/p>\n\n\n<style>.kb-progress-bar-container1117_89c475-17 .kb-progress-label-wrap{justify-content:space-between;}<\/style><div class=\"kb-progress-bar-container kb-progress-bar-container1117_89c475-17 kb-progress-bar-init kb-progress-bar-type-circle \"><div class=\"kb-progress-label-wrap\"><span id=\"current-progress-above1117_89c475-17\" class=\"kb-current-progress-above kt-progress-percent\">100%<\/span><\/div><div class=\"kb-progress-bar kb-progress-bar-1117_89c475-17\"><\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-1117_bf8dcc-b2 .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-1117_bf8dcc-b2 .kt-divider{border-top-width:6px;border-top-color:#1d1d1b;width:80%;border-top-style:dotted;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-1117_bf8dcc-b2\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-1117_97bc59-de .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-1117_97bc59-de .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-1117_97bc59-de\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Grapevine<\/strong><\/td><td>100% Nebbiolo<\/td><\/tr><tr><td><strong>Production area<\/strong><\/td><td>MG of Castellinaldo d&#8217;Alba Serra Zoanni &#8211; Roero<\/td><\/tr><tr><td><strong>Land<\/strong><\/td><td>white earth and tuff<\/td><\/tr><tr><td><strong>Exposure \/ Altitude<\/strong><\/td><td>south, southeast \/ 300 m<\/td><\/tr><tr><td><strong>Breeding \/ Pruning<\/strong><\/td><td>counter-espalier \/ Guyot<\/td><\/tr><tr><td><strong>Planting density<\/strong><\/td><td>5,000 vines per hectare<\/td><\/tr><tr><td><strong>Yield per hectare<\/strong><\/td><td>40hl<\/td><\/tr><tr><td><strong>Harvest<\/strong><\/td><td>Manual in mid-October<\/td><\/tr><tr><td><strong>Vinification<\/strong><\/td><td>18 to 20 days of maceration with frequent d\u00e9lestages and punching down; temperature controlled, maximum regime 28\u00b0C.<\/td><\/tr><tr><td><strong>Refinement<\/strong><\/td><td>24 months in tonneaux, 12 months in bottle<\/td><\/tr><tr><td><strong>Bottles per year<\/strong><\/td><td>2.000<\/td><\/tr><tr><td><strong>Pairings<\/strong><\/td><td>Roasted red meat, game, aged cheeses<\/td><\/tr><tr><td><strong>Formats<\/strong><\/td><td>0.75L &#8211; 1.5L<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-1117_fa1953-7d .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-1117_fa1953-7d .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-1117_fa1953-7d\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n<style>.kt-svg-icons1117_cde26e-bd .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons1117_cde26e-bd{justify-content:center;}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons1117_cde26e-bd alignnone\"><style>.kt-svg-item-1117_c31234-e3 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-1117_c31234-e3 .kb-svg-icon-wrap{color:#1d1d1b;font-size:40px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-1117_c31234-e3\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_file-download\"><svg viewBox=\"0 0 384 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"\/><\/svg><\/span><\/div>\n<\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kt-btns1117_74e2dd-40, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns1117_74e2dd-40, .wp-block-kadence-advancedbtn.kb-btns1117_74e2dd-40, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns1117_74e2dd-40{margin-top:var(--global-kb-spacing-sm, 1.5rem);margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}.wp-block-kadence-advancedbtn.kb-btns1117_74e2dd-40{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns1117_74e2dd-40 .kt-button{font-weight:normal;font-style:normal;}.kt-btns1117_74e2dd-40 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns1117_74e2dd-40 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns1117_74e2dd-40 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1117_74e2dd-40 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns1117_74e2dd-40 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns1117_74e2dd-40 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns1117_74e2dd-40 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns1117_74e2dd-40\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn1117_9a8ac1-15.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn1117_9a8ac1-15.kb-button{background:#1d1d1b;}.wp-block-kadence-advancedbtn .kb-btn1117_9a8ac1-15.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn1117_9a8ac1-15.kb-button:focus{color:var(--global-palette2, #2B6CB0);background:var(--global-palette3, #1A202C);}<\/style><a class=\"kb-button kt-button button kb-btn1117_9a8ac1-15 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-kadence-singlebtn\" href=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/serraZoanni-RoeroRiservaIta.pdf\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Download data sheet<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id1117_2ab9e9-5a > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1117_2ab9e9-5a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1117_2ab9e9-5a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1117_2ab9e9-5a > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1117_2ab9e9-5a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1117_2ab9e9-5a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1117_2ab9e9-5a alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1117_b44e8a-d4 > .kt-inside-inner-col,.kadence-column1117_b44e8a-d4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1117_b44e8a-d4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1117_b44e8a-d4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1117_b44e8a-d4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1117_b44e8a-d4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1117_b44e8a-d4{position:relative;}@media all and (max-width: 1024px){.kadence-column1117_b44e8a-d4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1117_b44e8a-d4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1117_b44e8a-d4\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-1117_a8ad6b-2e .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-1117_a8ad6b-2e .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-1117_a8ad6b-2e\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n<style>.wp-block-kadence-image.kb-image1117_69f772-a3:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image1117_69f772-a3.kb-image-is-ratio-size, .kb-image1117_69f772-a3 .kb-image-is-ratio-size{max-width:100px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image1117_69f772-a3.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image1117_69f772-a3 .kb-image-is-ratio-size{align-self:unset;}.kb-image1117_69f772-a3 figure{max-width:100px;}.kb-image1117_69f772-a3 .image-is-svg, .kb-image1117_69f772-a3 .image-is-svg img{width:100%;}.kb-image1117_69f772-a3 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image1117_69f772-a3\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/faq-cascinadelpozzo.png\" alt=\"Frequently Asked Questions FAQ - Cascina del Pozzo\" class=\"kb-img wp-image-796\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/faq-cascinadelpozzo.png 150w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/faq-cascinadelpozzo-100x100.png 100w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1117_4dc745-7e, .wp-block-kadence-advancedheading.kt-adv-heading1117_4dc745-7e[data-kb-block=\"kb-adv-heading1117_4dc745-7e\"]{margin-top:0px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1117_4dc745-7e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1117_4dc745-7e[data-kb-block=\"kb-adv-heading1117_4dc745-7e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1117_4dc745-7e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1117_4dc745-7e[data-kb-block=\"kb-adv-heading1117_4dc745-7e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading1117_4dc745-7e wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1117_4dc745-7e\">Frequently Asked Questions<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1117_31dee2-14, .wp-block-kadence-advancedheading.kt-adv-heading1117_31dee2-14[data-kb-block=\"kb-adv-heading1117_31dee2-14\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1117_31dee2-14 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1117_31dee2-14[data-kb-block=\"kb-adv-heading1117_31dee2-14\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1117_31dee2-14 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1117_31dee2-14[data-kb-block=\"kb-adv-heading1117_31dee2-14\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1117_31dee2-14 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1117_31dee2-14\">Curiosities and questions about <strong>Roero Riserva Serra Zoanni<\/strong> and related concepts<\/p>\n\n\n<style>.kb-row-layout-id1117_685299-b5 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1117_685299-b5 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1117_685299-b5 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:680px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1117_685299-b5 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1117_685299-b5 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1117_685299-b5 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1117_685299-b5 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1117_47624d-8d > .kt-inside-inner-col,.kadence-column1117_47624d-8d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1117_47624d-8d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1117_47624d-8d > .kt-inside-inner-col{flex-direction:column;}.kadence-column1117_47624d-8d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1117_47624d-8d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1117_47624d-8d{position:relative;}@media all and (max-width: 1024px){.kadence-column1117_47624d-8d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1117_47624d-8d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1117_47624d-8d\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id1117_ebe765-ac .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:0px;}.kt-accordion-id1117_ebe765-ac .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id1117_ebe765-ac > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:var(--global-palette8, #F7FAFC);color:#555555;padding-top:10px;padding-right:14px;padding-bottom:10px;padding-left:14px;}.kt-accordion-id1117_ebe765-ac:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1117_ebe765-ac:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#555555;}.kt-accordion-id1117_ebe765-ac:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#555555;}.kt-accordion-id1117_ebe765-ac:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1117_ebe765-ac:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette8, #F7FAFC);}.kt-accordion-id1117_ebe765-ac > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1117_ebe765-ac .kt-blocks-accordion-header:focus-visible{color:#444444;background:var(--global-palette7, #EDF2F7);border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id1117_ebe765-ac:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1117_ebe765-ac:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id1117_ebe765-ac:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id1117_ebe765-ac:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id1117_ebe765-ac:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id1117_ebe765-ac:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id1117_ebe765-ac:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1117_ebe765-ac:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id1117_ebe765-ac:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id1117_ebe765-ac:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette7, #EDF2F7);}.kt-accordion-id1117_ebe765-ac .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1117_ebe765-ac > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:var(--global-palette4, #2D3748);background:var(--global-palette2, #2B6CB0);border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id1117_ebe765-ac:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1117_ebe765-ac:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette4, #2D3748);}.kt-accordion-id1117_ebe765-ac:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:var(--global-palette4, #2D3748);}.kt-accordion-id1117_ebe765-ac:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1117_ebe765-ac:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette2, #2B6CB0);}@media all and (max-width: 1024px){.kt-accordion-id1117_ebe765-ac .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id1117_ebe765-ac > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}}@media all and (max-width: 1024px){.kt-accordion-id1117_ebe765-ac > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1117_ebe765-ac .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id1117_ebe765-ac .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1117_ebe765-ac > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id1117_ebe765-ac .kt-accordion-inner-wrap{display:block;}.kt-accordion-id1117_ebe765-ac .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:0px;}.kt-accordion-id1117_ebe765-ac .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id1117_ebe765-ac > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}.kt-accordion-id1117_ebe765-ac > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1117_ebe765-ac .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id1117_ebe765-ac .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1117_ebe765-ac > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id1117_ebe765-ac kt-accordion-has-5-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrow kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane1117_28a83f-c0\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">What sets this wine apart?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>The terrain of <strong>Serra Zoanni<\/strong> is very hard. The characteristic white soil with tuff produces a nebbiolo perfect to aging. It has a very intense color and very firm, hard tannins.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<style>.kt-accordion-id894_2b4313-e6 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:0px;}.kt-accordion-id894_2b4313-e6 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id894_2b4313-e6 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:var(--global-palette8, #F7FAFC);color:#555555;padding-top:10px;padding-right:14px;padding-bottom:10px;padding-left:14px;}.kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#555555;}.kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#555555;}.kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette8, #F7FAFC);}.kt-accordion-id894_2b4313-e6 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id894_2b4313-e6 .kt-blocks-accordion-header:focus-visible{color:#444444;background:var(--global-palette7, #EDF2F7);border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette7, #EDF2F7);}.kt-accordion-id894_2b4313-e6 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id894_2b4313-e6 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:var(--global-palette4, #2D3748);background:var(--global-palette2, #2B6CB0);border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette4, #2D3748);}.kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:var(--global-palette4, #2D3748);}.kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette2, #2B6CB0);}@media all and (max-width: 1024px){.kt-accordion-id894_2b4313-e6 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id894_2b4313-e6 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}}@media all and (max-width: 1024px){.kt-accordion-id894_2b4313-e6 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id894_2b4313-e6 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id894_2b4313-e6 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id894_2b4313-e6 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id894_2b4313-e6 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id894_2b4313-e6 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:0px;}.kt-accordion-id894_2b4313-e6 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id894_2b4313-e6 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}.kt-accordion-id894_2b4313-e6 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id894_2b4313-e6 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id894_2b4313-e6 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id894_2b4313-e6 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id894_2b4313-e6 kt-accordion-has-8-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrow kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-4 kt-pane894_c244cb-ae\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">What is a cru?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>A <strong>cru<\/strong>, from the French verb <em>cro\u00eetre<\/em> (to grow), means &#8220;that which grows in an area,&#8221; and indicates a specific vineyard in a given geographic region from which a particularly high-quality wine is made.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-6 kt-pane894_04cf69-75\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">What does cuv\u00e8e mean?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>The word cuv\u00e8e stands for a wine composed of the blending of several wines. By blending different wines, it is possible to balance the flavors and perfect the tastes expressed by the various crus. <\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-5 kt-pane894_878026-55\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">What is Guyot and which one is used at Cascina del Pozzo?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>The term guyot is named after its originator, Dr. Jules Guyot, who in the mid-19th century gave birth to this vine training system. Guyot at Cascina del Pozzo is the simple one so with only one head of fruit. On red wines we leave 6 to 8 buds depending on the vigor of the plant and a single spur of 2 buds for the following year. This leads to more quality and less quantity.   <\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-7 kt-pane894_50ba8d-5f\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">What does batonnage mean?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>Batonnage is a technique used to stir a fermenting wine that will then move on to barrel aging. The action brings the lees, that is, the yeast residues necessary for alcoholic fermentation, to the surface. Batonnage is traditionally carried out with a b\u00e2ton or &#8220;stick.&#8221;  <\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-8 kt-pane894_427e97-07\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">What does tonneaux mean?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>Tonneaux, from the Latin word &#8220;tunna,&#8221; means &#8220;cask&#8221; or &#8220;vessel.&#8221; These are wooden barrels, originating in the Bordeaux area of France, spread throughout the world, used for aging wine. <\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div><style>.wp-block-kadence-spacer.kt-block-spacer-1117_3d67a8-98 .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-1117_3d67a8-98 .kt-divider{border-top-width:6px;border-top-color:var(--global-palette4, #2D3748);width:80%;border-top-style:dotted;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-1117_3d67a8-98\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n<style>.kb-row-layout-id1117_8f2565-72 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1117_8f2565-72 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1117_8f2565-72 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1117_8f2565-72 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1117_8f2565-72 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1117_8f2565-72 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1117_8f2565-72 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1117_cc963d-8a > .kt-inside-inner-col,.kadence-column1117_cc963d-8a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1117_cc963d-8a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1117_cc963d-8a > .kt-inside-inner-col{flex-direction:column;}.kadence-column1117_cc963d-8a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1117_cc963d-8a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1117_cc963d-8a{position:relative;}@media all and (max-width: 1024px){.kadence-column1117_cc963d-8a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1117_cc963d-8a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1117_cc963d-8a\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1117_c44c11-75, .wp-block-kadence-advancedheading.kt-adv-heading1117_c44c11-75[data-kb-block=\"kb-adv-heading1117_c44c11-75\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1117_c44c11-75 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1117_c44c11-75[data-kb-block=\"kb-adv-heading1117_c44c11-75\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1117_c44c11-75 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1117_c44c11-75[data-kb-block=\"kb-adv-heading1117_c44c11-75\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading1117_c44c11-75 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1117_c44c11-75\">Vineyard: Serra Zoanni<\/h3>\n\n\n<style>.kb-image1117_77f163-e2.kb-image-is-ratio-size, .kb-image1117_77f163-e2 .kb-image-is-ratio-size{max-width:680px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image1117_77f163-e2.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image1117_77f163-e2 .kb-image-is-ratio-size{align-self:unset;}.kb-image1117_77f163-e2 figure{max-width:680px;}.kb-image1117_77f163-e2 .image-is-svg, .kb-image1117_77f163-e2 .image-is-svg img{width:100%;}.kb-image1117_77f163-e2 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image1117_77f163-e2\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"978\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/mappa-serrazoanni-roero.png\" alt=\"Map Serra Zoanni Roero Reserve\" class=\"kb-img wp-image-1130\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/mappa-serrazoanni-roero.png 1000w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/mappa-serrazoanni-roero-600x587.png 600w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/mappa-serrazoanni-roero-300x293.png 300w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/mappa-serrazoanni-roero-768x751.png 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/div>\n<\/div><\/div>\n\n<\/div><\/div><style>.kb-row-layout-id1117_f02c81-b8 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1117_f02c81-b8 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1117_f02c81-b8 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1117_f02c81-b8 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1117_f02c81-b8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1117_f02c81-b8 > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1117_f02c81-b8 alignnone has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1117_497b92-ae > .kt-inside-inner-col,.kadence-column1117_497b92-ae > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1117_497b92-ae > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1117_497b92-ae > .kt-inside-inner-col{flex-direction:column;}.kadence-column1117_497b92-ae > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1117_497b92-ae > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1117_497b92-ae{position:relative;}@media all and (max-width: 1024px){.kadence-column1117_497b92-ae > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1117_497b92-ae > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1117_497b92-ae\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-1117_4dadbe-69 .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-1117_4dadbe-69 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-1117_4dadbe-69\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1117_350a24-6f, .wp-block-kadence-advancedheading.kt-adv-heading1117_350a24-6f[data-kb-block=\"kb-adv-heading1117_350a24-6f\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1117_350a24-6f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1117_350a24-6f[data-kb-block=\"kb-adv-heading1117_350a24-6f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1117_350a24-6f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1117_350a24-6f[data-kb-block=\"kb-adv-heading1117_350a24-6f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading1117_350a24-6f wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1117_350a24-6f\">Pairings<\/h3>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-1117_37a350-54 .kt-block-spacer{height:10px;}.wp-block-kadence-spacer.kt-block-spacer-1117_37a350-54 .kt-divider{border-top-width:1px;height:1px;border-top-color:var(--global-palette2, #2B6CB0);width:40%;border-top-style:dashed;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-1117_37a350-54\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.kb-row-layout-id1117_05be08-ca > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1117_05be08-ca > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1117_05be08-ca > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:800px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}.kb-row-layout-id1117_05be08-ca > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1117_05be08-ca > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}}@media all and (max-width: 767px){.kb-row-layout-id1117_05be08-ca > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1117_05be08-ca alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1117_376a54-9c > .kt-inside-inner-col,.kadence-column1117_376a54-9c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1117_376a54-9c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1117_376a54-9c > .kt-inside-inner-col{flex-direction:column;}.kadence-column1117_376a54-9c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1117_376a54-9c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1117_376a54-9c{position:relative;}@media all and (max-width: 1024px){.kadence-column1117_376a54-9c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1117_376a54-9c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1117_376a54-9c\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1117_d10bb5-a7, .wp-block-kadence-advancedheading.kt-adv-heading1117_d10bb5-a7[data-kb-block=\"kb-adv-heading1117_d10bb5-a7\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1117_d10bb5-a7 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1117_d10bb5-a7[data-kb-block=\"kb-adv-heading1117_d10bb5-a7\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1117_d10bb5-a7 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1117_d10bb5-a7[data-kb-block=\"kb-adv-heading1117_d10bb5-a7\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading1117_d10bb5-a7 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1117_d10bb5-a7\">meat<\/h4>\n\n\n<style>.kb-image1117_36e6d5-e0 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image1117_36e6d5-e0 size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"453\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/arrosti.jpg\" alt=\"Roasts paired with wines\" class=\"kb-img wp-image-1127\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/arrosti.jpg 680w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/arrosti-600x400.jpg 600w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/arrosti-300x200.jpg 300w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column1117_638920-4f > .kt-inside-inner-col,.kadence-column1117_638920-4f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1117_638920-4f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1117_638920-4f > .kt-inside-inner-col{flex-direction:column;}.kadence-column1117_638920-4f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1117_638920-4f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1117_638920-4f{position:relative;}@media all and (max-width: 1024px){.kadence-column1117_638920-4f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1117_638920-4f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1117_638920-4f\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1117_e230c8-b8, .wp-block-kadence-advancedheading.kt-adv-heading1117_e230c8-b8[data-kb-block=\"kb-adv-heading1117_e230c8-b8\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1117_e230c8-b8 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1117_e230c8-b8[data-kb-block=\"kb-adv-heading1117_e230c8-b8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1117_e230c8-b8 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1117_e230c8-b8[data-kb-block=\"kb-adv-heading1117_e230c8-b8\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1117_e230c8-b8 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1117_e230c8-b8\"><strong>Roero Riserva Serra Zoanni<\/strong> pairs well with meat and aged cheeses. The following are some classics that are well compatible with this label:<\/p>\n\n\n<style>.kb-row-layout-id1117_d7f1ca-ee > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1117_d7f1ca-ee > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1117_d7f1ca-ee > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1117_d7f1ca-ee > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1117_d7f1ca-ee > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1117_d7f1ca-ee > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1117_d7f1ca-ee alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1117_b42d75-e2 > .kt-inside-inner-col,.kadence-column1117_b42d75-e2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1117_b42d75-e2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1117_b42d75-e2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1117_b42d75-e2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1117_b42d75-e2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1117_b42d75-e2{position:relative;}@media all and (max-width: 1024px){.kadence-column1117_b42d75-e2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1117_b42d75-e2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1117_b42d75-e2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1117_3fa722-8a:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1117_3fa722-8a ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1117_3fa722-8a ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1117_3fa722-8a .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}.wp-block-kadence-iconlist.kt-svg-icon-list-items1117_3fa722-8a ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1117_3fa722-8a ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1117_3fa722-8a kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1117_fcc56d-19 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1117_fcc56d-19\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_wine-glass-alt kt-svg-icon-list-single\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M216 464h-40V346.81c68.47-15.89 118.05-79.91 111.4-154.16l-15.95-178.1C270.71 6.31 263.9 0 255.74 0H32.26c-8.15 0-14.97 6.31-15.7 14.55L.6 192.66C-6.05 266.91 43.53 330.93 112 346.82V464H72c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h208c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM61.75 48h164.5l7.17 80H54.58l7.17-80z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Roast with potatoes<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1117_a34051-4b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1117_a34051-4b\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_wine-glass-alt kt-svg-icon-list-single\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M216 464h-40V346.81c68.47-15.89 118.05-79.91 111.4-154.16l-15.95-178.1C270.71 6.31 263.9 0 255.74 0H32.26c-8.15 0-14.97 6.31-15.7 14.55L.6 192.66C-6.05 266.91 43.53 330.93 112 346.82V464H72c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h208c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM61.75 48h164.5l7.17 80H54.58l7.17-80z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Venison loin with blackberry sauce<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1117_ebcde7-51 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1117_ebcde7-51\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_wine-glass-alt kt-svg-icon-list-single\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M216 464h-40V346.81c68.47-15.89 118.05-79.91 111.4-154.16l-15.95-178.1C270.71 6.31 263.9 0 255.74 0H32.26c-8.15 0-14.97 6.31-15.7 14.55L.6 192.66C-6.05 266.91 43.53 330.93 112 346.82V464H72c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h208c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM61.75 48h164.5l7.17 80H54.58l7.17-80z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Slices of venison and mushrooms<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1117_048a9c-d3 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1117_048a9c-d3\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_wine-glass-alt kt-svg-icon-list-single\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M216 464h-40V346.81c68.47-15.89 118.05-79.91 111.4-154.16l-15.95-178.1C270.71 6.31 263.9 0 255.74 0H32.26c-8.15 0-14.97 6.31-15.7 14.55L.6 192.66C-6.05 266.91 43.53 330.93 112 346.82V464H72c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h208c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM61.75 48h164.5l7.17 80H54.58l7.17-80z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">wild boar rolls in grappa sauce<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1117_b726ef-5a > .kt-inside-inner-col,.kadence-column1117_b726ef-5a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1117_b726ef-5a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1117_b726ef-5a > .kt-inside-inner-col{flex-direction:column;}.kadence-column1117_b726ef-5a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1117_b726ef-5a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1117_b726ef-5a{position:relative;}@media all and (max-width: 1024px){.kadence-column1117_b726ef-5a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1117_b726ef-5a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1117_b726ef-5a\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1117_fffc8b-ef:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1117_fffc8b-ef ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1117_fffc8b-ef ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1117_fffc8b-ef .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}.wp-block-kadence-iconlist.kt-svg-icon-list-items1117_fffc8b-ef ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1117_fffc8b-ef ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1117_fffc8b-ef kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1117_828043-63 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1117_828043-63\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_wine-glass-alt kt-svg-icon-list-single\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M216 464h-40V346.81c68.47-15.89 118.05-79.91 111.4-154.16l-15.95-178.1C270.71 6.31 263.9 0 255.74 0H32.26c-8.15 0-14.97 6.31-15.7 14.55L.6 192.66C-6.05 266.91 43.53 330.93 112 346.82V464H72c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h208c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM61.75 48h164.5l7.17 80H54.58l7.17-80z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Entrecote of venison in chestnut crust<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1117_67699f-78 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1117_67699f-78\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_wine-glass-alt kt-svg-icon-list-single\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M216 464h-40V346.81c68.47-15.89 118.05-79.91 111.4-154.16l-15.95-178.1C270.71 6.31 263.9 0 255.74 0H32.26c-8.15 0-14.97 6.31-15.7 14.55L.6 192.66C-6.05 266.91 43.53 330.93 112 346.82V464H72c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h208c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM61.75 48h164.5l7.17 80H54.58l7.17-80z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Hazelnut-crusted venison escalope with chanterelles<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1117_f079e0-00 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1117_f079e0-00\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_wine-glass-alt kt-svg-icon-list-single\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M216 464h-40V346.81c68.47-15.89 118.05-79.91 111.4-154.16l-15.95-178.1C270.71 6.31 263.9 0 255.74 0H32.26c-8.15 0-14.97 6.31-15.7 14.55L.6 192.66C-6.05 266.91 43.53 330.93 112 346.82V464H72c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h208c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM61.75 48h164.5l7.17 80H54.58l7.17-80z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Cinnamon squash mince<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-1117_d1b9f5-d9 .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-1117_d1b9f5-d9 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-1117_d1b9f5-d9\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-1117_b088b1-f3 .kt-block-spacer{height:10px;}.wp-block-kadence-spacer.kt-block-spacer-1117_b088b1-f3 .kt-divider{border-top-width:1px;height:1px;border-top-color:var(--global-palette2, #2B6CB0);width:40%;border-top-style:dashed;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-1117_b088b1-f3\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Roero Riserva Serra Zoanni First vintage: 2017 With the arrival of geographical mentions, we wanted to vinify separately the nebbiolo vineyard planted in the 1960s. Serra Zoanni comes from clay-rich soil and is distinguished from Montegalletto by its spicy and intense aromatics, but also by soft, silky and persistent tannin. Roero Riserva Serra Zoanni Nebbiolo&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2164,"parent":2329,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-2355","page","type-page","status-publish","has-post-thumbnail","hentry"],"taxonomy_info":[],"featured_image_src_large":["https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/roero-riserva-serra-zoanni.png",500,884,false],"author_info":{"display_name":"admin","author_link":"https:\/\/cascinadelpozzo.com\/en\/author\/admin\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/cascinadelpozzo.com\/en\/wp-json\/wp\/v2\/pages\/2355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cascinadelpozzo.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cascinadelpozzo.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cascinadelpozzo.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cascinadelpozzo.com\/en\/wp-json\/wp\/v2\/comments?post=2355"}],"version-history":[{"count":2,"href":"https:\/\/cascinadelpozzo.com\/en\/wp-json\/wp\/v2\/pages\/2355\/revisions"}],"predecessor-version":[{"id":2541,"href":"https:\/\/cascinadelpozzo.com\/en\/wp-json\/wp\/v2\/pages\/2355\/revisions\/2541"}],"up":[{"embeddable":true,"href":"https:\/\/cascinadelpozzo.com\/en\/wp-json\/wp\/v2\/pages\/2329"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cascinadelpozzo.com\/en\/wp-json\/wp\/v2\/media\/2164"}],"wp:attachment":[{"href":"https:\/\/cascinadelpozzo.com\/en\/wp-json\/wp\/v2\/media?parent=2355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}