{"id":852,"date":"2023-10-05T14:04:19","date_gmt":"2023-10-05T14:04:19","guid":{"rendered":"https:\/\/cascinadelpozzo.com\/?page_id=852"},"modified":"2024-11-25T11:12:04","modified_gmt":"2024-11-25T10:12:04","slug":"decimo-rosa","status":"publish","type":"page","link":"https:\/\/cascinadelpozzo.com\/it\/vini\/decimo-rosa\/","title":{"rendered":"Decimo Rosa"},"content":{"rendered":"<style>.kb-row-layout-id852_20ffea-2a > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id852_20ffea-2a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id852_20ffea-2a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id852_20ffea-2a{background-image:url('https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/09\/uva-vite.cascinadelpozzo.jpg');background-size:cover;background-position:center center;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id852_20ffea-2a > .kt-row-layout-overlay{opacity:0.75;background-color:var(--global-palette4, #2D3748);}@media all and (max-width: 1024px){.kb-row-layout-id852_20ffea-2a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id852_20ffea-2a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id852_20ffea-2a alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column852_53e58f-cc > .kt-inside-inner-col,.kadence-column852_53e58f-cc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column852_53e58f-cc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column852_53e58f-cc > .kt-inside-inner-col{flex-direction:column;}.kadence-column852_53e58f-cc > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column852_53e58f-cc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column852_53e58f-cc{position:relative;}@media all and (max-width: 1024px){.kadence-column852_53e58f-cc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column852_53e58f-cc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column852_53e58f-cc\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-852_5e7630-23 .kt-block-spacer{height:100px;}.wp-block-kadence-spacer.kt-block-spacer-852_5e7630-23 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-852_5e7630-23\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading852_30f163-95, .wp-block-kadence-advancedheading.kt-adv-heading852_30f163-95[data-kb-block=\"kb-adv-heading852_30f163-95\"]{text-align:center;font-style:normal;color:#ee7796;}.wp-block-kadence-advancedheading.kt-adv-heading852_30f163-95 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading852_30f163-95[data-kb-block=\"kb-adv-heading852_30f163-95\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading852_30f163-95 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading852_30f163-95[data-kb-block=\"kb-adv-heading852_30f163-95\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h1 class=\"kt-adv-heading852_30f163-95 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading852_30f163-95\">DECIMO ROSA Spumante Brut<\/h1>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading852_20c419-f5, .wp-block-kadence-advancedheading.kt-adv-heading852_20c419-f5[data-kb-block=\"kb-adv-heading852_20c419-f5\"]{text-align:center;font-style:normal;color:#ee7796;}.wp-block-kadence-advancedheading.kt-adv-heading852_20c419-f5 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading852_20c419-f5[data-kb-block=\"kb-adv-heading852_20c419-f5\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading852_20c419-f5 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading852_20c419-f5[data-kb-block=\"kb-adv-heading852_20c419-f5\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading852_20c419-f5 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading852_20c419-f5\">Metodo Martinotti<\/h3>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-852_da8068-85 .kt-block-spacer{height:100px;}.wp-block-kadence-spacer.kt-block-spacer-852_da8068-85 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-852_da8068-85\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id852_2dfbc7-ae > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id852_2dfbc7-ae > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id852_2dfbc7-ae > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id852_2dfbc7-ae > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id852_2dfbc7-ae > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id852_2dfbc7-ae > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id852_2dfbc7-ae alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column852_51708c-4d > .kt-inside-inner-col,.kadence-column852_51708c-4d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column852_51708c-4d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column852_51708c-4d > .kt-inside-inner-col{flex-direction:column;}.kadence-column852_51708c-4d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column852_51708c-4d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column852_51708c-4d{position:relative;}@media all and (max-width: 1024px){.kadence-column852_51708c-4d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column852_51708c-4d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column852_51708c-4d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-852_ad0366-be .kt-block-spacer{height:40px;}.wp-block-kadence-spacer.kt-block-spacer-852_ad0366-be .kt-divider{border-top-width:4px;border-top-color:#ee7796;width:35%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-852_ad0366-be\"><div class=\"kt-block-spacer kt-block-spacer-halign-left\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.kb-row-layout-id852_c11590-4e > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id852_c11590-4e > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id852_c11590-4e > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id852_c11590-4e > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id852_c11590-4e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id852_c11590-4e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id852_c11590-4e alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column852_5423ef-c3 > .kt-inside-inner-col{display:flex;}.kadence-column852_5423ef-c3 > .kt-inside-inner-col,.kadence-column852_5423ef-c3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column852_5423ef-c3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column852_5423ef-c3 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}.kadence-column852_5423ef-c3 > .kt-inside-inner-col > *, .kadence-column852_5423ef-c3 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column852_5423ef-c3 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column852_5423ef-c3 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kadence-column852_5423ef-c3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column852_5423ef-c3{position:relative;}@media all and (max-width: 1024px){.kadence-column852_5423ef-c3 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column852_5423ef-c3 > .kt-inside-inner-col > *, .kadence-column852_5423ef-c3 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column852_5423ef-c3 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column852_5423ef-c3 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kadence-column852_5423ef-c3 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column852_5423ef-c3 > .kt-inside-inner-col > *, .kadence-column852_5423ef-c3 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column852_5423ef-c3 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column852_5423ef-c3 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column852_5423ef-c3 kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.kt-svg-icons852_431043-06 .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons852_431043-06{justify-content:center;}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons852_431043-06 alignnone\"><style>.kt-svg-item-852_c678fe-45 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-852_c678fe-45 .kb-svg-icon-wrap{color:var(--global-palette1, #3182CE);font-size:15px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-852_c678fe-45\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_info-circle\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M256 8C119.043 8 8 119.083 8 256c0 136.997 111.043 248 248 248s248-111.003 248-248C504 119.083 392.957 8 256 8zm0 110c23.196 0 42 18.804 42 42s-18.804 42-42 42-42-18.804-42-42 18.804-42 42-42zm56 254c0 6.627-5.373 12-12 12h-88c-6.627 0-12-5.373-12-12v-24c0-6.627 5.373-12 12-12h12v-64h-12c-6.627 0-12-5.373-12-12v-24c0-6.627 5.373-12 12-12h64c6.627 0 12 5.373 12 12v100h12c6.627 0 12 5.373 12 12v24z\"\/><\/svg><\/span><\/div>\n<\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading852_e17283-d1, .wp-block-kadence-advancedheading.kt-adv-heading852_e17283-d1[data-kb-block=\"kb-adv-heading852_e17283-d1\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading852_e17283-d1 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading852_e17283-d1[data-kb-block=\"kb-adv-heading852_e17283-d1\"] mark.kt-highlight{font-style:normal;color:var(--global-palette1, #3182CE);-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading852_e17283-d1 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading852_e17283-d1[data-kb-block=\"kb-adv-heading852_e17283-d1\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading852_e17283-d1 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading852_e17283-d1\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-theme-palette-8-color\"><mark style=\"\" class=\"kt-highlight\"><strong style=\"background-color: rgba(0, 0, 0, 0);\">Prima annata<\/strong>: <\/mark><\/mark><em>2020<\/em><\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading852_2ff018-ec, .wp-block-kadence-advancedheading.kt-adv-heading852_2ff018-ec[data-kb-block=\"kb-adv-heading852_2ff018-ec\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading852_2ff018-ec mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading852_2ff018-ec[data-kb-block=\"kb-adv-heading852_2ff018-ec\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading852_2ff018-ec img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading852_2ff018-ec[data-kb-block=\"kb-adv-heading852_2ff018-ec\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading852_2ff018-ec wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading852_2ff018-ec\">E&#8217; in ordine cronologico il nostro terzo spumante, un&#8217;etichetta nata dall&#8217;esigenza di stare al passo coi tempi. Il colore rosa buccia di cipolla \u00e8 frutto di una precisa macerazione a freddo del Pinot Nero. Il risultato \u00e8 una bollicina fresca e piacevole, morbida e poco invadente.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading852_49baf5-87, .wp-block-kadence-advancedheading.kt-adv-heading852_49baf5-87[data-kb-block=\"kb-adv-heading852_49baf5-87\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading852_49baf5-87 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading852_49baf5-87[data-kb-block=\"kb-adv-heading852_49baf5-87\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading852_49baf5-87 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading852_49baf5-87[data-kb-block=\"kb-adv-heading852_49baf5-87\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading852_49baf5-87 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading852_49baf5-87\">Al naso i sentori di frutta della macerazione si legano a quelli dell&#8217;arneis e dello chardonnay, mentre all&#8217;assaggio \u00e8 molto delicato e allo stesso tempo persistente.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading852_419b12-c8, .wp-block-kadence-advancedheading.kt-adv-heading852_419b12-c8[data-kb-block=\"kb-adv-heading852_419b12-c8\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading852_419b12-c8 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading852_419b12-c8[data-kb-block=\"kb-adv-heading852_419b12-c8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading852_419b12-c8 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading852_419b12-c8[data-kb-block=\"kb-adv-heading852_419b12-c8\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading852_419b12-c8 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading852_419b12-c8\">Per i pi\u00f9 appassionati di ros\u00e8 abbiamo lasciato un piccolo consiglio nella parte interna della retro etichetta, andate a dare un occhiata!<\/p>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-852_46592e-f9 .kt-block-spacer{height:30px;}.wp-block-kadence-spacer.kt-block-spacer-852_46592e-f9 .kt-divider{border-top-width:4px;border-top-color:#ee7796;width:100%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-852_46592e-f9\"><div class=\"kt-block-spacer kt-block-spacer-halign-left\"><hr class=\"kt-divider\"\/><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column852_de5ae2-24 > .kt-inside-inner-col{display:flex;}.kadence-column852_de5ae2-24 > .kt-inside-inner-col,.kadence-column852_de5ae2-24 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column852_de5ae2-24 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column852_de5ae2-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column852_de5ae2-24 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column852_de5ae2-24{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column852_de5ae2-24{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column852_de5ae2-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column852_de5ae2-24 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column852_de5ae2-24{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column852_de5ae2-24{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column852_de5ae2-24{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column852_de5ae2-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column852_de5ae2-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column852_de5ae2-24{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column852_de5ae2-24{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column852_de5ae2-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column852_de5ae2-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column852_de5ae2-24\"><div class=\"kt-inside-inner-col\"><style>.kb-image852_9cd1e1-c7.kb-image-is-ratio-size, .kb-image852_9cd1e1-c7 .kb-image-is-ratio-size{max-width:280px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image852_9cd1e1-c7.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image852_9cd1e1-c7 .kb-image-is-ratio-size{align-self:unset;}.kb-image852_9cd1e1-c7 figure{max-width:280px;}.kb-image852_9cd1e1-c7 .image-is-svg, .kb-image852_9cd1e1-c7 .image-is-svg img{width:100%;}.kb-image852_9cd1e1-c7 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kb-image852_9cd1e1-c7 img.kb-img, .kb-image852_9cd1e1-c7 .kb-img img{border-top:4px solid var(--global-palette7, #EDF2F7);border-right:4px solid var(--global-palette7, #EDF2F7);border-bottom:4px solid var(--global-palette7, #EDF2F7);border-left:4px solid var(--global-palette7, #EDF2F7);border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}@media all and (max-width: 1024px){.kb-image852_9cd1e1-c7 img.kb-img, .kb-image852_9cd1e1-c7 .kb-img img{border-top:4px solid var(--global-palette7, #EDF2F7);border-right:4px solid var(--global-palette7, #EDF2F7);border-bottom:4px solid var(--global-palette7, #EDF2F7);border-left:4px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.kb-image852_9cd1e1-c7 img.kb-img, .kb-image852_9cd1e1-c7 .kb-img img{border-top:4px solid var(--global-palette7, #EDF2F7);border-right:4px solid var(--global-palette7, #EDF2F7);border-bottom:4px solid var(--global-palette7, #EDF2F7);border-left:4px solid var(--global-palette7, #EDF2F7);}}<\/style>\n<div class=\"wp-block-kadence-image kb-image852_9cd1e1-c7\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"577\" height=\"1024\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/decimo-rosa-cascinadelpozzo-577x1024.jpg\" alt=\"Spumante Brut Decimo Rosa Cascina del Pozzo Castellinaldo d'Alba (CN) Roero\" class=\"kb-img wp-image-853\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/decimo-rosa-cascinadelpozzo-577x1024.jpg 577w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/decimo-rosa-cascinadelpozzo-600x1066.jpg 600w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/decimo-rosa-cascinadelpozzo-169x300.jpg 169w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/decimo-rosa-cascinadelpozzo-768x1364.jpg 768w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/decimo-rosa-cascinadelpozzo-865x1536.jpg 865w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/decimo-rosa-cascinadelpozzo-1153x2048.jpg 1153w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/decimo-rosa-cascinadelpozzo.jpg 1250w\" sizes=\"auto, (max-width: 577px) 100vw, 577px\" \/><\/figure><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id852_6b0db2-17 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id852_6b0db2-17 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id852_6b0db2-17 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:800px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id852_6b0db2-17 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id852_6b0db2-17 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id852_6b0db2-17 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id852_6b0db2-17 alignnone has-theme-palette7-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column852_1e7ee7-99 > .kt-inside-inner-col,.kadence-column852_1e7ee7-99 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column852_1e7ee7-99 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column852_1e7ee7-99 > .kt-inside-inner-col{flex-direction:column;}.kadence-column852_1e7ee7-99 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column852_1e7ee7-99 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column852_1e7ee7-99{position:relative;}@media all and (max-width: 1024px){.kadence-column852_1e7ee7-99 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column852_1e7ee7-99 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column852_1e7ee7-99\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading852_e11813-1e, .wp-block-kadence-advancedheading.kt-adv-heading852_e11813-1e[data-kb-block=\"kb-adv-heading852_e11813-1e\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading852_e11813-1e mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading852_e11813-1e[data-kb-block=\"kb-adv-heading852_e11813-1e\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading852_e11813-1e img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading852_e11813-1e[data-kb-block=\"kb-adv-heading852_e11813-1e\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading852_e11813-1e wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading852_e11813-1e\">DECIMO ROSA<\/h2>\n\n\n<style>.kb-row-layout-id852_d50e24-04 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id852_d50e24-04 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id852_d50e24-04 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id852_d50e24-04 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id852_d50e24-04 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id852_d50e24-04 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id852_d50e24-04 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id852_d50e24-04 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id852_d50e24-04 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id852_d50e24-04 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id852_d50e24-04 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column852_b20d60-8a > .kt-inside-inner-col{padding-right:var(--global-kb-spacing-xl, 4rem);padding-left:var(--global-kb-spacing-xl, 4rem);}.kadence-column852_b20d60-8a > .kt-inside-inner-col{border-right:2px dotted #ee7796;}.kadence-column852_b20d60-8a > .kt-inside-inner-col,.kadence-column852_b20d60-8a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column852_b20d60-8a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column852_b20d60-8a > .kt-inside-inner-col{flex-direction:column;}.kadence-column852_b20d60-8a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column852_b20d60-8a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column852_b20d60-8a{position:relative;}@media all and (max-width: 1024px){.kadence-column852_b20d60-8a > .kt-inside-inner-col{border-right:2px dotted #ee7796;flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column852_b20d60-8a > .kt-inside-inner-col{border-right:2px dotted #ee7796;flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column852_b20d60-8a\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading852_1411e4-86, .wp-block-kadence-advancedheading.kt-adv-heading852_1411e4-86[data-kb-block=\"kb-adv-heading852_1411e4-86\"]{margin-bottom:0px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading852_1411e4-86 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading852_1411e4-86[data-kb-block=\"kb-adv-heading852_1411e4-86\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading852_1411e4-86 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading852_1411e4-86[data-kb-block=\"kb-adv-heading852_1411e4-86\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading852_1411e4-86 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading852_1411e4-86\"><strong>Pinot nero<\/strong><\/p>\n\n\n<style>.kb-progress-bar-container852_af8376-2d .kb-progress-label-wrap{justify-content:space-between;}<\/style><div class=\"kb-progress-bar-container kb-progress-bar-container852_af8376-2d kb-progress-bar-init kb-progress-bar-type-circle \"><div class=\"kb-progress-label-wrap\"><span id=\"current-progress-above852_af8376-2d\" class=\"kb-current-progress-above kt-progress-percent\">50%<\/span><\/div><div class=\"kb-progress-bar kb-progress-bar-852_af8376-2d\"><\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column852_3f088a-39 > .kt-inside-inner-col{padding-right:var(--global-kb-spacing-xl, 4rem);padding-left:var(--global-kb-spacing-xl, 4rem);}.kadence-column852_3f088a-39 > .kt-inside-inner-col{border-right:2px dotted #ee7796;}.kadence-column852_3f088a-39 > .kt-inside-inner-col,.kadence-column852_3f088a-39 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column852_3f088a-39 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column852_3f088a-39 > .kt-inside-inner-col{flex-direction:column;}.kadence-column852_3f088a-39 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column852_3f088a-39 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column852_3f088a-39{position:relative;}@media all and (max-width: 1024px){.kadence-column852_3f088a-39 > .kt-inside-inner-col{border-right:2px dotted #ee7796;flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column852_3f088a-39 > .kt-inside-inner-col{border-right:2px dotted #ee7796;flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column852_3f088a-39\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading852_5c14bb-16, .wp-block-kadence-advancedheading.kt-adv-heading852_5c14bb-16[data-kb-block=\"kb-adv-heading852_5c14bb-16\"]{margin-bottom:0px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading852_5c14bb-16 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading852_5c14bb-16[data-kb-block=\"kb-adv-heading852_5c14bb-16\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading852_5c14bb-16 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading852_5c14bb-16[data-kb-block=\"kb-adv-heading852_5c14bb-16\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading852_5c14bb-16 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading852_5c14bb-16\"><strong>Arneis<\/strong><\/p>\n\n\n<style>.kb-progress-bar-container852_282c1c-6a .kb-progress-label-wrap{justify-content:space-between;}<\/style><div class=\"kb-progress-bar-container kb-progress-bar-container852_282c1c-6a kb-progress-bar-init kb-progress-bar-type-circle \"><div class=\"kb-progress-label-wrap\"><span id=\"current-progress-above852_282c1c-6a\" class=\"kb-current-progress-above kt-progress-percent\">25%<\/span><\/div><div class=\"kb-progress-bar kb-progress-bar-852_282c1c-6a\"><\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column852_afdcd1-22 > .kt-inside-inner-col{padding-right:var(--global-kb-spacing-xl, 4rem);padding-left:var(--global-kb-spacing-xl, 4rem);}.kadence-column852_afdcd1-22 > .kt-inside-inner-col,.kadence-column852_afdcd1-22 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column852_afdcd1-22 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column852_afdcd1-22 > .kt-inside-inner-col{flex-direction:column;}.kadence-column852_afdcd1-22 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column852_afdcd1-22 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column852_afdcd1-22{position:relative;}@media all and (max-width: 1024px){.kadence-column852_afdcd1-22 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column852_afdcd1-22 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column852_afdcd1-22\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading852_4d5898-01, .wp-block-kadence-advancedheading.kt-adv-heading852_4d5898-01[data-kb-block=\"kb-adv-heading852_4d5898-01\"]{margin-bottom:0px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading852_4d5898-01 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading852_4d5898-01[data-kb-block=\"kb-adv-heading852_4d5898-01\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading852_4d5898-01 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading852_4d5898-01[data-kb-block=\"kb-adv-heading852_4d5898-01\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading852_4d5898-01 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading852_4d5898-01\"><strong>Chardonnay<\/strong><\/p>\n\n\n<style>.kb-progress-bar-container852_6facb9-07 .kb-progress-label-wrap{justify-content:space-between;}<\/style><div class=\"kb-progress-bar-container kb-progress-bar-container852_6facb9-07 kb-progress-bar-init kb-progress-bar-type-circle \"><div class=\"kb-progress-label-wrap\"><span id=\"current-progress-above852_6facb9-07\" class=\"kb-current-progress-above kt-progress-percent\">25%<\/span><\/div><div class=\"kb-progress-bar kb-progress-bar-852_6facb9-07\"><\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-852_eeba99-e4 .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-852_eeba99-e4 .kt-divider{border-top-width:6px;border-top-color:#ee7796;width:80%;border-top-style:dotted;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-852_eeba99-e4\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-852_4cf1df-bf .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-852_4cf1df-bf .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-852_4cf1df-bf\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Vitigno<\/strong><\/td><td>Pinot nero 50%, Arneis 25%, Chardonnay 25%<\/td><\/tr><tr><td><strong>Area di produzione<\/strong><\/td><td>Castellinaldo d&#8217;Alba &#8211; Roero<\/td><\/tr><tr><td><strong>Terreno<\/strong><\/td><td>Sabbioso con basse percentuali di limo e argilla<\/td><\/tr><tr><td><strong>Esposizione \/ Altitudine<\/strong><\/td><td>280 &#8211; 330 m<\/td><\/tr><tr><td><strong>Allevamento \/ Potatura<\/strong><\/td><td>Controspalliera \/ Guyot<\/td><\/tr><tr><td><strong>Densit\u00e0 d&#8217;impianto<\/strong><\/td><td>5.000 viti per ettaro<\/td><\/tr><tr><td><strong>Resa per ettaro<\/strong><\/td><td>70hl<\/td><\/tr><tr><td><strong>Vendemmia<\/strong><\/td><td>Manuale a fine agosto o inizio settembre<\/td><\/tr><tr><td><strong>Vinificazione<\/strong><\/td><td>Pressatura soffice; macerazione sulle bucce di Pinot Nero per 24 ore; fermentazione alcolica in acciaio Inox termocondizionato; regime massimo 17\u00b0; protezione dall&#8217;ossigeno; spumantizzato con metodo Charmat.<\/td><\/tr><tr><td><strong>Affinamento<\/strong><\/td><td>3 mesi in botti in acciaio Inox con batonnages periodici.<\/td><\/tr><tr><td><strong>Bottiglie annue<\/strong><\/td><td>12.000<\/td><\/tr><tr><td><strong>Abbinamenti<\/strong><\/td><td>Piatti di pesce, antipasti delicati, verdure gratinate, formaggi freschi.<\/td><\/tr><tr><td><strong>Formati<\/strong><\/td><td>0,75L &#8211; 1,5L<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-852_795e77-fb .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-852_795e77-fb .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-852_795e77-fb\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n<style>.kt-svg-icons852_1c6e26-b1 .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons852_1c6e26-b1{justify-content:center;}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons852_1c6e26-b1 alignnone\"><style>.kt-svg-item-852_4733a6-fd .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-852_4733a6-fd .kb-svg-icon-wrap{color:#ee7796;font-size:40px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-852_4733a6-fd\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_file-download\"><svg viewBox=\"0 0 384 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"\/><\/svg><\/span><\/div>\n<\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kt-btns852_3fd1dc-38, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns852_3fd1dc-38, .wp-block-kadence-advancedbtn.kb-btns852_3fd1dc-38, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns852_3fd1dc-38{margin-top:var(--global-kb-spacing-sm, 1.5rem);margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}.wp-block-kadence-advancedbtn.kb-btns852_3fd1dc-38{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns852_3fd1dc-38 .kt-button{font-weight:normal;font-style:normal;}.kt-btns852_3fd1dc-38 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns852_3fd1dc-38 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns852_3fd1dc-38 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns852_3fd1dc-38 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns852_3fd1dc-38 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns852_3fd1dc-38 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns852_3fd1dc-38 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns852_3fd1dc-38\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn852_a5d4ff-59.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn852_a5d4ff-59.kb-button{background:#ee7796;}.wp-block-kadence-advancedbtn .kb-btn852_a5d4ff-59.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn852_a5d4ff-59.kb-button:focus{background:#dd6e8a;}<\/style><a class=\"kb-button kt-button button kb-btn852_a5d4ff-59 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-kadence-singlebtn\" href=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/SpumanteDecimoRosa.pdf\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Download scheda tecnica<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id852_750e9f-17 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id852_750e9f-17 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id852_750e9f-17 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id852_750e9f-17 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id852_750e9f-17 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id852_750e9f-17 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id852_750e9f-17 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column852_3d3e59-6f > .kt-inside-inner-col,.kadence-column852_3d3e59-6f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column852_3d3e59-6f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column852_3d3e59-6f > .kt-inside-inner-col{flex-direction:column;}.kadence-column852_3d3e59-6f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column852_3d3e59-6f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column852_3d3e59-6f{position:relative;}@media all and (max-width: 1024px){.kadence-column852_3d3e59-6f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column852_3d3e59-6f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column852_3d3e59-6f\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-852_50e716-73 .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-852_50e716-73 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-852_50e716-73\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n<style>.wp-block-kadence-image.kb-image852_a68ed4-02:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image852_a68ed4-02.kb-image-is-ratio-size, .kb-image852_a68ed4-02 .kb-image-is-ratio-size{max-width:100px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image852_a68ed4-02.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image852_a68ed4-02 .kb-image-is-ratio-size{align-self:unset;}.kb-image852_a68ed4-02 figure{max-width:100px;}.kb-image852_a68ed4-02 .image-is-svg, .kb-image852_a68ed4-02 .image-is-svg img{width:100%;}.kb-image852_a68ed4-02 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image852_a68ed4-02\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/faq-cascinadelpozzo.png\" alt=\"Domande Frequenti FAQ - Cascina del Pozzo\" class=\"kb-img wp-image-796\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/faq-cascinadelpozzo.png 150w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/faq-cascinadelpozzo-100x100.png 100w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading852_521cc8-78, .wp-block-kadence-advancedheading.kt-adv-heading852_521cc8-78[data-kb-block=\"kb-adv-heading852_521cc8-78\"]{margin-top:0px;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading852_521cc8-78 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading852_521cc8-78[data-kb-block=\"kb-adv-heading852_521cc8-78\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading852_521cc8-78 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading852_521cc8-78[data-kb-block=\"kb-adv-heading852_521cc8-78\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading852_521cc8-78 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading852_521cc8-78\">Domande Frequenti<\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading852_9bdd73-90, .wp-block-kadence-advancedheading.kt-adv-heading852_9bdd73-90[data-kb-block=\"kb-adv-heading852_9bdd73-90\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading852_9bdd73-90 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading852_9bdd73-90[data-kb-block=\"kb-adv-heading852_9bdd73-90\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading852_9bdd73-90 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading852_9bdd73-90[data-kb-block=\"kb-adv-heading852_9bdd73-90\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading852_9bdd73-90 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading852_9bdd73-90\">Curiosit\u00e0 e domande sullo <strong>Spumante Brut Decimo Rosa<\/strong> e concetti relativi<\/p>\n\n\n<style>.kb-row-layout-id852_4e4ef6-80 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id852_4e4ef6-80 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id852_4e4ef6-80 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:680px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id852_4e4ef6-80 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id852_4e4ef6-80 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id852_4e4ef6-80 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id852_4e4ef6-80 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column852_59b7ea-d4 > .kt-inside-inner-col,.kadence-column852_59b7ea-d4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column852_59b7ea-d4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column852_59b7ea-d4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column852_59b7ea-d4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column852_59b7ea-d4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column852_59b7ea-d4{position:relative;}@media all and (max-width: 1024px){.kadence-column852_59b7ea-d4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column852_59b7ea-d4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column852_59b7ea-d4\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id852_d5be58-29 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:0px;}.kt-accordion-id852_d5be58-29 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id852_d5be58-29 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:var(--global-palette8, #F7FAFC);color:#555555;padding-top:10px;padding-right:14px;padding-bottom:10px;padding-left:14px;}.kt-accordion-id852_d5be58-29:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id852_d5be58-29:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#555555;}.kt-accordion-id852_d5be58-29:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#555555;}.kt-accordion-id852_d5be58-29:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id852_d5be58-29:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette8, #F7FAFC);}.kt-accordion-id852_d5be58-29 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id852_d5be58-29 .kt-blocks-accordion-header:focus-visible{color:#444444;background:var(--global-palette7, #EDF2F7);border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id852_d5be58-29:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id852_d5be58-29:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id852_d5be58-29:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id852_d5be58-29:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id852_d5be58-29:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id852_d5be58-29:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id852_d5be58-29:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id852_d5be58-29:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id852_d5be58-29:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id852_d5be58-29:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette7, #EDF2F7);}.kt-accordion-id852_d5be58-29 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id852_d5be58-29 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:var(--global-palette4, #2D3748);background:var(--global-palette2, #2B6CB0);border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id852_d5be58-29:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id852_d5be58-29:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette4, #2D3748);}.kt-accordion-id852_d5be58-29:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:var(--global-palette4, #2D3748);}.kt-accordion-id852_d5be58-29:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id852_d5be58-29:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette2, #2B6CB0);}@media all and (max-width: 1024px){.kt-accordion-id852_d5be58-29 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id852_d5be58-29 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}}@media all and (max-width: 1024px){.kt-accordion-id852_d5be58-29 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id852_d5be58-29 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id852_d5be58-29 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id852_d5be58-29 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id852_d5be58-29 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id852_d5be58-29 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:0px;}.kt-accordion-id852_d5be58-29 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id852_d5be58-29 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}.kt-accordion-id852_d5be58-29 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id852_d5be58-29 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id852_d5be58-29 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id852_d5be58-29 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id852_d5be58-29 kt-accordion-has-5-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrow kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane852_c94b60-ee\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Cosa contraddistingue questo vino?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>E&#8217; un Ros\u00e8 moderno che nel 2023 scocca la quarta vendemmia. Il contatto con le bucce del vino rosso Pinot Nero dona la sua caratteristica colorazione rosea.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane852_20f53d-67\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Cosa significa &#8220;Metodo Martinotti&#8221; ?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>La modalit\u00e0 di produzione dello spumante Decimo \u00e8 perfezionata col metodo Martinotti-Charmat, nome dedicato a Federico Martinotti, di Villanova Monferrato (Piemonte, provincia di Alessandria) che nel 1895 invent\u00f2 la rifermentazione controllata in autoclave. &#8220;Charmat&#8221; perch\u00e8 nel 1910 il francese Eug\u00e9ne Charmat costru\u00ec e brevett\u00f2 tale attrezzatura.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading852_a4d0b7-ed, .wp-block-kadence-advancedheading.kt-adv-heading852_a4d0b7-ed[data-kb-block=\"kb-adv-heading852_a4d0b7-ed\"]{margin-top:var(--global-kb-spacing-sm, 1.5rem);font-size:var(--global-kb-font-size-sm, 0.9rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading852_a4d0b7-ed mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading852_a4d0b7-ed[data-kb-block=\"kb-adv-heading852_a4d0b7-ed\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading852_a4d0b7-ed img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading852_a4d0b7-ed[data-kb-block=\"kb-adv-heading852_a4d0b7-ed\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading852_a4d0b7-ed wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading852_a4d0b7-ed\">Wikipedia: <a href=\"https:\/\/it.wikipedia.org\/wiki\/Metodo_Martinotti\" target=\"_blank\" rel=\"noopener\">https:\/\/it.wikipedia.org\/wiki\/Metodo_Martinotti<\/a> <\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<style>.kt-accordion-id894_2b4313-e6 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:0px;}.kt-accordion-id894_2b4313-e6 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id894_2b4313-e6 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:var(--global-palette8, #F7FAFC);color:#555555;padding-top:10px;padding-right:14px;padding-bottom:10px;padding-left:14px;}.kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#555555;}.kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#555555;}.kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette8, #F7FAFC);}.kt-accordion-id894_2b4313-e6 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id894_2b4313-e6 .kt-blocks-accordion-header:focus-visible{color:#444444;background:var(--global-palette7, #EDF2F7);border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette7, #EDF2F7);}.kt-accordion-id894_2b4313-e6 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id894_2b4313-e6 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:var(--global-palette4, #2D3748);background:var(--global-palette2, #2B6CB0);border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette4, #2D3748);}.kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:var(--global-palette4, #2D3748);}.kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id894_2b4313-e6:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette2, #2B6CB0);}@media all and (max-width: 1024px){.kt-accordion-id894_2b4313-e6 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id894_2b4313-e6 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}}@media all and (max-width: 1024px){.kt-accordion-id894_2b4313-e6 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id894_2b4313-e6 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id894_2b4313-e6 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id894_2b4313-e6 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id894_2b4313-e6 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id894_2b4313-e6 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:0px;}.kt-accordion-id894_2b4313-e6 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id894_2b4313-e6 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #f2f2f2;border-right:0px solid #f2f2f2;border-bottom:0px solid #f2f2f2;border-left:0px solid #f2f2f2;}.kt-accordion-id894_2b4313-e6 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id894_2b4313-e6 .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id894_2b4313-e6 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id894_2b4313-e6 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id894_2b4313-e6 kt-accordion-has-8-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrow kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-4 kt-pane894_c244cb-ae\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Cosa \u00e8 un cru?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>Un <strong>cru<\/strong>, dal verbo francese <em>cro\u00eetre<\/em> (crescere), significa &#8220;quello che cresce in una zona&#8221; e indica uno specifico vigneto di una determinata regione geografica dalla quale si ottiene un vino particolarmente di qualit\u00e0.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-6 kt-pane894_04cf69-75\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Cosa vuol dire cuv\u00e8e?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>La parola cuv\u00e8e sta a indicare un vino composto dalla miscela di pi\u00f9 vini. Mescolando vini diversi \u00e8 possibile equilibrare i sapori e perfezionare i gusti espressi dai vari cru.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-5 kt-pane894_878026-55\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Cosa \u00e8 il Guyot e quale viene usato alla Cascina del Pozzo?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>Il termine guyot prende il nome dal suo ideatore, il Dott. Jules Guyot che verso la met\u00e0 XIX secolo ha dato vita a questo sistema di allevamento della vite. Il guyot alla Cascina del Pozzo \u00e8 quello semplice quindi con un solo capofrutto. Sui vini rossi lasciamo dalle 6 alle 8 gemme a seconda del vigore della pianta e un solo sperone di 2 gemme per l&#8217;anno successivo. Questo porta ad avere pi\u00f9 qualit\u00e0 e meno quantit\u00e0.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-7 kt-pane894_50ba8d-5f\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Cosa significa batonnage?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>Il batonnage \u00e8 una tecnica utilizzata per rimescolare un vino in fermentazione che poi passer\u00e0 alla fase di affinamento in barrique. L&#8217;azione riporta le fecce, ossia i residui dei lieviti necessari alla fermentazione alcolica, in superficie. Il batonnage viene per tradizione effettuato con il b\u00e2ton o \u201cbastone\u201d.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-8 kt-pane894_427e97-07\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Cosa significa tonneaux?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>Tonneaux, dal latino \u201ctunna\u201d, significa \u201cbotte\u201d o \u201crecipiente\u201d. Sono botti di legno, originarie della zona di Bordeaux, in Francia, diffuse in tutto il mondo, utilizzate per l\u2019affinamento del vino.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-852_abd8af-fa .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-852_abd8af-fa .kt-divider{border-top-width:6px;border-top-color:#ee7796;width:80%;border-top-style:dotted;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-852_abd8af-fa\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.kb-row-layout-id852_18784f-b1 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id852_18784f-b1 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id852_18784f-b1 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id852_18784f-b1 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id852_18784f-b1 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id852_18784f-b1 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id852_18784f-b1 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column852_60f00c-07 > .kt-inside-inner-col,.kadence-column852_60f00c-07 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column852_60f00c-07 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column852_60f00c-07 > .kt-inside-inner-col{flex-direction:column;}.kadence-column852_60f00c-07 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column852_60f00c-07 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column852_60f00c-07{position:relative;}@media all and (max-width: 1024px){.kadence-column852_60f00c-07 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column852_60f00c-07 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column852_60f00c-07\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading852_93f59b-42, .wp-block-kadence-advancedheading.kt-adv-heading852_93f59b-42[data-kb-block=\"kb-adv-heading852_93f59b-42\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading852_93f59b-42 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading852_93f59b-42[data-kb-block=\"kb-adv-heading852_93f59b-42\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading852_93f59b-42 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading852_93f59b-42[data-kb-block=\"kb-adv-heading852_93f59b-42\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading852_93f59b-42 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading852_93f59b-42\">Vigneto: MEGA Leschera<\/h3>\n\n\n<style>.kb-image852_c7c218-c7.kb-image-is-ratio-size, .kb-image852_c7c218-c7 .kb-image-is-ratio-size{max-width:680px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image852_c7c218-c7.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image852_c7c218-c7 .kb-image-is-ratio-size{align-self:unset;}.kb-image852_c7c218-c7 figure{max-width:680px;}.kb-image852_c7c218-c7 .image-is-svg, .kb-image852_c7c218-c7 .image-is-svg img{width:100%;}.kb-image852_c7c218-c7 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image852_c7c218-c7\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"978\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2024\/11\/zonadiproduzionevino-decimo-megaleschera.png\" alt=\"MEGA Leschera - zona di produzione Decimo\" class=\"kb-img wp-image-2612\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2024\/11\/zonadiproduzionevino-decimo-megaleschera.png 1000w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2024\/11\/zonadiproduzionevino-decimo-megaleschera-300x293.png 300w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2024\/11\/zonadiproduzionevino-decimo-megaleschera-768x751.png 768w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2024\/11\/zonadiproduzionevino-decimo-megaleschera-600x587.png 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id852_eb1a40-82 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id852_eb1a40-82 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id852_eb1a40-82 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id852_eb1a40-82 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id852_eb1a40-82 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id852_eb1a40-82 > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id852_eb1a40-82 alignnone has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column852_d83160-11 > .kt-inside-inner-col,.kadence-column852_d83160-11 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column852_d83160-11 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column852_d83160-11 > .kt-inside-inner-col{flex-direction:column;}.kadence-column852_d83160-11 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column852_d83160-11 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column852_d83160-11{position:relative;}@media all and (max-width: 1024px){.kadence-column852_d83160-11 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column852_d83160-11 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column852_d83160-11\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-spacer.kt-block-spacer-852_5450f9-3c .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-852_5450f9-3c .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-852_5450f9-3c\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading852_ea8bc1-90, .wp-block-kadence-advancedheading.kt-adv-heading852_ea8bc1-90[data-kb-block=\"kb-adv-heading852_ea8bc1-90\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading852_ea8bc1-90 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading852_ea8bc1-90[data-kb-block=\"kb-adv-heading852_ea8bc1-90\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading852_ea8bc1-90 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading852_ea8bc1-90[data-kb-block=\"kb-adv-heading852_ea8bc1-90\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h3 class=\"kt-adv-heading852_ea8bc1-90 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading852_ea8bc1-90\">Abbinamenti<\/h3>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-852_c4dde0-ee .kt-block-spacer{height:10px;}.wp-block-kadence-spacer.kt-block-spacer-852_c4dde0-ee .kt-divider{border-top-width:1px;height:1px;border-top-color:var(--global-palette2, #2B6CB0);width:40%;border-top-style:dashed;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-852_c4dde0-ee\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.kb-row-layout-id852_641a1c-9b > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id852_641a1c-9b > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id852_641a1c-9b > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:800px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}.kb-row-layout-id852_641a1c-9b > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id852_641a1c-9b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}}@media all and (max-width: 767px){.kb-row-layout-id852_641a1c-9b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id852_641a1c-9b alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column852_3d236e-89 > .kt-inside-inner-col,.kadence-column852_3d236e-89 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column852_3d236e-89 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column852_3d236e-89 > .kt-inside-inner-col{flex-direction:column;}.kadence-column852_3d236e-89 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column852_3d236e-89 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column852_3d236e-89{position:relative;}@media all and (max-width: 1024px){.kadence-column852_3d236e-89 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column852_3d236e-89 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column852_3d236e-89\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading852_0f1cb7-d9, .wp-block-kadence-advancedheading.kt-adv-heading852_0f1cb7-d9[data-kb-block=\"kb-adv-heading852_0f1cb7-d9\"]{text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading852_0f1cb7-d9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading852_0f1cb7-d9[data-kb-block=\"kb-adv-heading852_0f1cb7-d9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading852_0f1cb7-d9 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading852_0f1cb7-d9[data-kb-block=\"kb-adv-heading852_0f1cb7-d9\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading852_0f1cb7-d9 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading852_0f1cb7-d9\">Pesce<\/h4>\n\n\n<style>.kb-image852_6e4319-2b .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image852_6e4319-2b size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/piatto-di-pesce-abbinato-vino-cascinadelpozzo-castellinaldo-alba-roero.jpg\" alt=\"Piatto di pesce abbinato a un vino della Cascina del Pozzo di Castellinaldo d'Alba (CN) - Roero.\" class=\"kb-img wp-image-817\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/piatto-di-pesce-abbinato-vino-cascinadelpozzo-castellinaldo-alba-roero.jpg 800w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/piatto-di-pesce-abbinato-vino-cascinadelpozzo-castellinaldo-alba-roero-300x300.jpg 300w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/piatto-di-pesce-abbinato-vino-cascinadelpozzo-castellinaldo-alba-roero-100x100.jpg 100w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/piatto-di-pesce-abbinato-vino-cascinadelpozzo-castellinaldo-alba-roero-600x600.jpg 600w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/piatto-di-pesce-abbinato-vino-cascinadelpozzo-castellinaldo-alba-roero-150x150.jpg 150w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/piatto-di-pesce-abbinato-vino-cascinadelpozzo-castellinaldo-alba-roero-768x768.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column852_8623ff-d0 > .kt-inside-inner-col,.kadence-column852_8623ff-d0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column852_8623ff-d0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column852_8623ff-d0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column852_8623ff-d0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column852_8623ff-d0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column852_8623ff-d0{position:relative;}@media all and (max-width: 1024px){.kadence-column852_8623ff-d0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column852_8623ff-d0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column852_8623ff-d0\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading852_86dac2-66, .wp-block-kadence-advancedheading.kt-adv-heading852_86dac2-66[data-kb-block=\"kb-adv-heading852_86dac2-66\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading852_86dac2-66 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading852_86dac2-66[data-kb-block=\"kb-adv-heading852_86dac2-66\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading852_86dac2-66 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading852_86dac2-66[data-kb-block=\"kb-adv-heading852_86dac2-66\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading852_86dac2-66 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading852_86dac2-66\">Lo <strong>Spumante Brut Decimo<\/strong> si abbina bene con piatti di pesce. Di seguito alcuni classici ben compatibili con questa etichetta:<\/p>\n\n\n<style>.kb-row-layout-id852_43b0f2-1c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id852_43b0f2-1c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id852_43b0f2-1c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id852_43b0f2-1c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id852_43b0f2-1c > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id852_43b0f2-1c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id852_43b0f2-1c alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column852_7452b6-e5 > .kt-inside-inner-col,.kadence-column852_7452b6-e5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column852_7452b6-e5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column852_7452b6-e5 > .kt-inside-inner-col{flex-direction:column;}.kadence-column852_7452b6-e5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column852_7452b6-e5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column852_7452b6-e5{position:relative;}@media all and (max-width: 1024px){.kadence-column852_7452b6-e5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column852_7452b6-e5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column852_7452b6-e5\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items852_5fecb4-bd:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items852_5fecb4-bd ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items852_5fecb4-bd ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items852_5fecb4-bd .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}.wp-block-kadence-iconlist.kt-svg-icon-list-items852_5fecb4-bd ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items852_5fecb4-bd ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items852_5fecb4-bd kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-852_061719-4a .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-852_061719-4a\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_wine-glass-alt kt-svg-icon-list-single\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M216 464h-40V346.81c68.47-15.89 118.05-79.91 111.4-154.16l-15.95-178.1C270.71 6.31 263.9 0 255.74 0H32.26c-8.15 0-14.97 6.31-15.7 14.55L.6 192.66C-6.05 266.91 43.53 330.93 112 346.82V464H72c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h208c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM61.75 48h164.5l7.17 80H54.58l7.17-80z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Filetto di persico al forno<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-852_e7950a-e2 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-852_e7950a-e2\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_wine-glass-alt kt-svg-icon-list-single\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M216 464h-40V346.81c68.47-15.89 118.05-79.91 111.4-154.16l-15.95-178.1C270.71 6.31 263.9 0 255.74 0H32.26c-8.15 0-14.97 6.31-15.7 14.55L.6 192.66C-6.05 266.91 43.53 330.93 112 346.82V464H72c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h208c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM61.75 48h164.5l7.17 80H54.58l7.17-80z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Orata al cartoccio<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-852_3bac9f-95 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-852_3bac9f-95\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_wine-glass-alt kt-svg-icon-list-single\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M216 464h-40V346.81c68.47-15.89 118.05-79.91 111.4-154.16l-15.95-178.1C270.71 6.31 263.9 0 255.74 0H32.26c-8.15 0-14.97 6.31-15.7 14.55L.6 192.66C-6.05 266.91 43.53 330.93 112 346.82V464H72c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h208c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM61.75 48h164.5l7.17 80H54.58l7.17-80z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Salmone in padella<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-852_a2f3b0-a1 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-852_a2f3b0-a1\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_wine-glass-alt kt-svg-icon-list-single\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M216 464h-40V346.81c68.47-15.89 118.05-79.91 111.4-154.16l-15.95-178.1C270.71 6.31 263.9 0 255.74 0H32.26c-8.15 0-14.97 6.31-15.7 14.55L.6 192.66C-6.05 266.91 43.53 330.93 112 346.82V464H72c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h208c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM61.75 48h164.5l7.17 80H54.58l7.17-80z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Platessa panata<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-852_0d14fa-43 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-852_0d14fa-43\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_wine-glass-alt kt-svg-icon-list-single\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M216 464h-40V346.81c68.47-15.89 118.05-79.91 111.4-154.16l-15.95-178.1C270.71 6.31 263.9 0 255.74 0H32.26c-8.15 0-14.97 6.31-15.7 14.55L.6 192.66C-6.05 266.91 43.53 330.93 112 346.82V464H72c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h208c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM61.75 48h164.5l7.17 80H54.58l7.17-80z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Gamberoni al forno<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column852_d539d2-e0 > .kt-inside-inner-col,.kadence-column852_d539d2-e0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column852_d539d2-e0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column852_d539d2-e0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column852_d539d2-e0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column852_d539d2-e0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column852_d539d2-e0{position:relative;}@media all and (max-width: 1024px){.kadence-column852_d539d2-e0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column852_d539d2-e0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column852_d539d2-e0\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items852_907ede-9a:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items852_907ede-9a ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items852_907ede-9a ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items852_907ede-9a .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}.wp-block-kadence-iconlist.kt-svg-icon-list-items852_907ede-9a ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items852_907ede-9a ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items852_907ede-9a kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-852_cfcd99-07 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-852_cfcd99-07\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_wine-glass-alt kt-svg-icon-list-single\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M216 464h-40V346.81c68.47-15.89 118.05-79.91 111.4-154.16l-15.95-178.1C270.71 6.31 263.9 0 255.74 0H32.26c-8.15 0-14.97 6.31-15.7 14.55L.6 192.66C-6.05 266.91 43.53 330.93 112 346.82V464H72c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h208c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM61.75 48h164.5l7.17 80H54.58l7.17-80z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Polpette di merluzzo<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-852_36709c-39 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-852_36709c-39\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_wine-glass-alt kt-svg-icon-list-single\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M216 464h-40V346.81c68.47-15.89 118.05-79.91 111.4-154.16l-15.95-178.1C270.71 6.31 263.9 0 255.74 0H32.26c-8.15 0-14.97 6.31-15.7 14.55L.6 192.66C-6.05 266.91 43.53 330.93 112 346.82V464H72c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h208c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM61.75 48h164.5l7.17 80H54.58l7.17-80z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Aragosta al forno<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-852_44c116-0a .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-852_44c116-0a\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_wine-glass-alt kt-svg-icon-list-single\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M216 464h-40V346.81c68.47-15.89 118.05-79.91 111.4-154.16l-15.95-178.1C270.71 6.31 263.9 0 255.74 0H32.26c-8.15 0-14.97 6.31-15.7 14.55L.6 192.66C-6.05 266.91 43.53 330.93 112 346.82V464H72c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h208c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM61.75 48h164.5l7.17 80H54.58l7.17-80z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Tonno in crosta di pistacchi<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-852_cce738-89 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-852_cce738-89\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_wine-glass-alt kt-svg-icon-list-single\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M216 464h-40V346.81c68.47-15.89 118.05-79.91 111.4-154.16l-15.95-178.1C270.71 6.31 263.9 0 255.74 0H32.26c-8.15 0-14.97 6.31-15.7 14.55L.6 192.66C-6.05 266.91 43.53 330.93 112 346.82V464H72c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h208c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM61.75 48h164.5l7.17 80H54.58l7.17-80z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Pesce spada al forno<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id852_0cfccd-53 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id852_0cfccd-53 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id852_0cfccd-53 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:800px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}.kb-row-layout-id852_0cfccd-53 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id852_0cfccd-53 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}}@media all and (max-width: 767px){.kb-row-layout-id852_0cfccd-53 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id852_0cfccd-53 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column852_c63ffe-d6 > .kt-inside-inner-col,.kadence-column852_c63ffe-d6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column852_c63ffe-d6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column852_c63ffe-d6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column852_c63ffe-d6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column852_c63ffe-d6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column852_c63ffe-d6{position:relative;}@media all and (max-width: 1024px){.kadence-column852_c63ffe-d6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column852_c63ffe-d6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column852_c63ffe-d6\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading852_2540b9-24, .wp-block-kadence-advancedheading.kt-adv-heading852_2540b9-24[data-kb-block=\"kb-adv-heading852_2540b9-24\"]{text-align:center;font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading852_2540b9-24 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading852_2540b9-24[data-kb-block=\"kb-adv-heading852_2540b9-24\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading852_2540b9-24 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading852_2540b9-24[data-kb-block=\"kb-adv-heading852_2540b9-24\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading852_2540b9-24 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading852_2540b9-24\">Antipasti delicati<\/h4>\n\n\n<style>.kb-image852_9c04d9-e9 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image852_9c04d9-e9 size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/antipasti-delicati-abbinati-vino-cascinadelpozzo-castellinaldo-alba-roero.jpg\" alt=\"Antipasti delicati abbinati al vino della Cascina del Pozzo (CN) - Zona del Roero in Castellinaldo d'Alba\" class=\"kb-img wp-image-828\" srcset=\"https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/antipasti-delicati-abbinati-vino-cascinadelpozzo-castellinaldo-alba-roero.jpg 800w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/antipasti-delicati-abbinati-vino-cascinadelpozzo-castellinaldo-alba-roero-300x300.jpg 300w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/antipasti-delicati-abbinati-vino-cascinadelpozzo-castellinaldo-alba-roero-100x100.jpg 100w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/antipasti-delicati-abbinati-vino-cascinadelpozzo-castellinaldo-alba-roero-600x600.jpg 600w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/antipasti-delicati-abbinati-vino-cascinadelpozzo-castellinaldo-alba-roero-150x150.jpg 150w, https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/10\/antipasti-delicati-abbinati-vino-cascinadelpozzo-castellinaldo-alba-roero-768x768.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column852_328465-7b > .kt-inside-inner-col,.kadence-column852_328465-7b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column852_328465-7b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column852_328465-7b > .kt-inside-inner-col{flex-direction:column;}.kadence-column852_328465-7b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column852_328465-7b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column852_328465-7b{position:relative;}@media all and (max-width: 1024px){.kadence-column852_328465-7b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column852_328465-7b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column852_328465-7b\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading852_a42ac7-76, .wp-block-kadence-advancedheading.kt-adv-heading852_a42ac7-76[data-kb-block=\"kb-adv-heading852_a42ac7-76\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading852_a42ac7-76 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading852_a42ac7-76[data-kb-block=\"kb-adv-heading852_a42ac7-76\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading852_a42ac7-76 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading852_a42ac7-76[data-kb-block=\"kb-adv-heading852_a42ac7-76\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading852_a42ac7-76 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading852_a42ac7-76\">Lo <strong>Spumante Brut Decimo<\/strong> \u00e8 ideale per antipasti delicati. Di seguito alcuni esempi:<\/p>\n\n\n<style>.kb-row-layout-id852_34c8d8-90 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id852_34c8d8-90 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id852_34c8d8-90 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id852_34c8d8-90 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id852_34c8d8-90 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id852_34c8d8-90 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id852_34c8d8-90 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column852_b1ff3b-0d > .kt-inside-inner-col,.kadence-column852_b1ff3b-0d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column852_b1ff3b-0d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column852_b1ff3b-0d > .kt-inside-inner-col{flex-direction:column;}.kadence-column852_b1ff3b-0d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column852_b1ff3b-0d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column852_b1ff3b-0d{position:relative;}@media all and (max-width: 1024px){.kadence-column852_b1ff3b-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column852_b1ff3b-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column852_b1ff3b-0d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items852_133364-8f:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items852_133364-8f ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items852_133364-8f ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items852_133364-8f .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}.wp-block-kadence-iconlist.kt-svg-icon-list-items852_133364-8f ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items852_133364-8f ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items852_133364-8f kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-852_5f7293-76 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-852_5f7293-76\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_wine-glass-alt kt-svg-icon-list-single\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M216 464h-40V346.81c68.47-15.89 118.05-79.91 111.4-154.16l-15.95-178.1C270.71 6.31 263.9 0 255.74 0H32.26c-8.15 0-14.97 6.31-15.7 14.55L.6 192.66C-6.05 266.91 43.53 330.93 112 346.82V464H72c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h208c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM61.75 48h164.5l7.17 80H54.58l7.17-80z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Focaccia genovese<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-852_a4084f-dc .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-852_a4084f-dc\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_wine-glass-alt kt-svg-icon-list-single\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M216 464h-40V346.81c68.47-15.89 118.05-79.91 111.4-154.16l-15.95-178.1C270.71 6.31 263.9 0 255.74 0H32.26c-8.15 0-14.97 6.31-15.7 14.55L.6 192.66C-6.05 266.91 43.53 330.93 112 346.82V464H72c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h208c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM61.75 48h164.5l7.17 80H54.58l7.17-80z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Salsa guacamole<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-852_df99f4-85 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-852_df99f4-85\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_wine-glass-alt kt-svg-icon-list-single\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M216 464h-40V346.81c68.47-15.89 118.05-79.91 111.4-154.16l-15.95-178.1C270.71 6.31 263.9 0 255.74 0H32.26c-8.15 0-14.97 6.31-15.7 14.55L.6 192.66C-6.05 266.91 43.53 330.93 112 346.82V464H72c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h208c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM61.75 48h164.5l7.17 80H54.58l7.17-80z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Salmone in padella<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-852_d13c52-55 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-852_d13c52-55\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_wine-glass-alt kt-svg-icon-list-single\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M216 464h-40V346.81c68.47-15.89 118.05-79.91 111.4-154.16l-15.95-178.1C270.71 6.31 263.9 0 255.74 0H32.26c-8.15 0-14.97 6.31-15.7 14.55L.6 192.66C-6.05 266.91 43.53 330.93 112 346.82V464H72c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h208c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM61.75 48h164.5l7.17 80H54.58l7.17-80z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Hummus<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-852_abfe55-c8 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-852_abfe55-c8\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_wine-glass-alt kt-svg-icon-list-single\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M216 464h-40V346.81c68.47-15.89 118.05-79.91 111.4-154.16l-15.95-178.1C270.71 6.31 263.9 0 255.74 0H32.26c-8.15 0-14.97 6.31-15.7 14.55L.6 192.66C-6.05 266.91 43.53 330.93 112 346.82V464H72c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h208c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM61.75 48h164.5l7.17 80H54.58l7.17-80z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Vitello tonnato<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column852_0c4763-55 > .kt-inside-inner-col,.kadence-column852_0c4763-55 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column852_0c4763-55 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column852_0c4763-55 > .kt-inside-inner-col{flex-direction:column;}.kadence-column852_0c4763-55 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column852_0c4763-55 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column852_0c4763-55{position:relative;}@media all and (max-width: 1024px){.kadence-column852_0c4763-55 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column852_0c4763-55 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column852_0c4763-55\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-iconlist.kt-svg-icon-list-items852_6a861e-d1:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items852_6a861e-d1 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items852_6a861e-d1 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items852_6a861e-d1 .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}.wp-block-kadence-iconlist.kt-svg-icon-list-items852_6a861e-d1 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items852_6a861e-d1 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items852_6a861e-d1 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-852_c48a49-c9 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-852_c48a49-c9\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_wine-glass-alt kt-svg-icon-list-single\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M216 464h-40V346.81c68.47-15.89 118.05-79.91 111.4-154.16l-15.95-178.1C270.71 6.31 263.9 0 255.74 0H32.26c-8.15 0-14.97 6.31-15.7 14.55L.6 192.66C-6.05 266.91 43.53 330.93 112 346.82V464H72c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h208c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM61.75 48h164.5l7.17 80H54.58l7.17-80z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Panzerotti fritti<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-852_ab7e57-67 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-852_ab7e57-67\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_wine-glass-alt kt-svg-icon-list-single\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M216 464h-40V346.81c68.47-15.89 118.05-79.91 111.4-154.16l-15.95-178.1C270.71 6.31 263.9 0 255.74 0H32.26c-8.15 0-14.97 6.31-15.7 14.55L.6 192.66C-6.05 266.91 43.53 330.93 112 346.82V464H72c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h208c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM61.75 48h164.5l7.17 80H54.58l7.17-80z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Polppette alle melanzane<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-852_c036e9-ff .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-852_c036e9-ff\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_wine-glass-alt kt-svg-icon-list-single\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M216 464h-40V346.81c68.47-15.89 118.05-79.91 111.4-154.16l-15.95-178.1C270.71 6.31 263.9 0 255.74 0H32.26c-8.15 0-14.97 6.31-15.7 14.55L.6 192.66C-6.05 266.91 43.53 330.93 112 346.82V464H72c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h208c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM61.75 48h164.5l7.17 80H54.58l7.17-80z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Mozzarelle in carrozza<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-852_f5b39b-95 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-852_f5b39b-95\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_wine-glass-alt kt-svg-icon-list-single\"><svg viewBox=\"0 0 288 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M216 464h-40V346.81c68.47-15.89 118.05-79.91 111.4-154.16l-15.95-178.1C270.71 6.31 263.9 0 255.74 0H32.26c-8.15 0-14.97 6.31-15.7 14.55L.6 192.66C-6.05 266.91 43.53 330.93 112 346.82V464H72c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h208c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM61.75 48h164.5l7.17 80H54.58l7.17-80z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Insalata di polpo<\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-852_395a83-23 .kt-block-spacer{height:20px;}.wp-block-kadence-spacer.kt-block-spacer-852_395a83-23 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-852_395a83-23\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading852_57a1f1-26, .wp-block-kadence-advancedheading.kt-adv-heading852_57a1f1-26[data-kb-block=\"kb-adv-heading852_57a1f1-26\"]{margin-bottom:var(--global-kb-spacing-md, 2rem);text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading852_57a1f1-26 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading852_57a1f1-26[data-kb-block=\"kb-adv-heading852_57a1f1-26\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading852_57a1f1-26 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading852_57a1f1-26[data-kb-block=\"kb-adv-heading852_57a1f1-26\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading852_57a1f1-26 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading852_57a1f1-26\">Inoltre lo <strong>Spumante Brut Decimo Rosa<\/strong> si abbina bene con verdure gratinate e formaggi freschi<\/p>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-852_888f60-e0 .kt-block-spacer{height:10px;}.wp-block-kadence-spacer.kt-block-spacer-852_888f60-e0 .kt-divider{border-top-width:1px;height:1px;border-top-color:var(--global-palette2, #2B6CB0);width:40%;border-top-style:dashed;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-852_888f60-e0\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>DECIMO ROSA Spumante Brut Metodo Martinotti Prima annata: 2020 E&#8217; in ordine cronologico il nostro terzo spumante, un&#8217;etichetta nata dall&#8217;esigenza di stare al passo coi tempi. Il colore rosa buccia di cipolla \u00e8 frutto di una precisa macerazione a freddo del Pinot Nero. Il risultato \u00e8 una bollicina fresca e piacevole, morbida e poco invadente&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":1165,"parent":730,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"enable","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-852","page","type-page","status-publish","has-post-thumbnail","hentry"],"taxonomy_info":[],"featured_image_src_large":["https:\/\/cascinadelpozzo.com\/wp-content\/uploads\/2023\/11\/spumante-brut-decimo-rosa-cascinadelpozzo.png",500,884,false],"author_info":{"display_name":"admin","author_link":"https:\/\/cascinadelpozzo.com\/it\/author\/admin\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/cascinadelpozzo.com\/it\/wp-json\/wp\/v2\/pages\/852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cascinadelpozzo.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cascinadelpozzo.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cascinadelpozzo.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cascinadelpozzo.com\/it\/wp-json\/wp\/v2\/comments?post=852"}],"version-history":[{"count":16,"href":"https:\/\/cascinadelpozzo.com\/it\/wp-json\/wp\/v2\/pages\/852\/revisions"}],"predecessor-version":[{"id":2618,"href":"https:\/\/cascinadelpozzo.com\/it\/wp-json\/wp\/v2\/pages\/852\/revisions\/2618"}],"up":[{"embeddable":true,"href":"https:\/\/cascinadelpozzo.com\/it\/wp-json\/wp\/v2\/pages\/730"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cascinadelpozzo.com\/it\/wp-json\/wp\/v2\/media\/1165"}],"wp:attachment":[{"href":"https:\/\/cascinadelpozzo.com\/it\/wp-json\/wp\/v2\/media?parent=852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}